{"id":10772,"date":"2024-09-09T04:05:22","date_gmt":"2024-09-09T02:05:22","guid":{"rendered":"https:\/\/shop.ptm-mechatronics.com\/stage\/?post_type=grundlagen-guide&#038;p=10772"},"modified":"2024-10-07T09:10:36","modified_gmt":"2024-10-07T07:10:36","slug":"waermeuebertragung","status":"publish","type":"grundlagen-guide","link":"https:\/\/ptm-mechatronics.com\/sk\/grundlagen-guide\/waermeuebertragung\/","title":{"rendered":"Prenos tepla"},"content":{"rendered":"<div class=\"row\"  id=\"row-779485414\">\n\n\t<div id=\"col-250645329\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Prenos tepla zah\u0155\u0148a udr\u017eiavanie kon\u0161tantnej teploty m\u00e9dia, jej zvy\u0161ovanie alebo zni\u017eovanie po\u010das procesu mie\u0161ania. Pou\u017e\u00edvaj\u00fa sa n\u00e1dr\u017ee \u0161peci\u00e1lne navrhnut\u00e9 na regul\u00e1ciu teploty. Ke\u010f\u017ee prenos tepla cez stenu n\u00e1dr\u017ee \u010dasto nie je dostato\u010dn\u00fd, musia sa do mie\u0161acej n\u00e1dr\u017ee nain\u0161talova\u0165 \u010fal\u0161ie prvky v\u00fdmeny tepla, ako s\u00fa mie\u0161acie \u0161pir\u00e1ly, vykurovacie alebo chladiace svie\u010dky a in\u00e9 \u0161peci\u00e1lne kon\u0161trukcie. Samotn\u00e9 mie\u0161adlo a kon\u0161trukcia musia by\u0165 tie\u017e navrhnut\u00e9 tak, aby vyhovovali procesu prenosu tepla a boli schopn\u00e9 odol\u00e1va\u0165 teplot\u00e1m.<\/p>\n<p>Mie\u0161adl\u00e1 na prenos tepla sa preto \u010dasto prisp\u00f4sobuj\u00fa individu\u00e1lnym po\u017eiadavk\u00e1m na zmes a na dosiahnutie optim\u00e1lneho v\u00fdsledku. Mie\u0161adl\u00e1 PTM m\u00f4\u017eu by\u0165 navrhnut\u00e9 pre teploty a\u017e do 300 \u00b0C. Na po\u017eiadanie v\u00e1m m\u00f4\u017eeme navrhn\u00fa\u0165 a vyrobi\u0165 aj kompletn\u00fd syst\u00e9m so zladen\u00fdmi komponentmi.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1558598753\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_420688142\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"785\" height=\"585\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/09\/Agitator-with-special-flange-for-temperature-control-middle-position-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/09\/Agitator-with-special-flange-for-temperature-control-middle-position-1.jpg 785w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/09\/Agitator-with-special-flange-for-temperature-control-middle-position-1-300x224.jpg 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/09\/Agitator-with-special-flange-for-temperature-control-middle-position-1-768x572.jpg 768w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/09\/Agitator-with-special-flange-for-temperature-control-middle-position-1-100x75.jpg 100w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/09\/Agitator-with-special-flange-for-temperature-control-middle-position-1-447x333.jpg 447w\" sizes=\"auto, (max-width: 785px) 100vw, 785px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_420688142 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Prenos tepla zah\u0155\u0148a udr\u017eiavanie kon\u0161tantnej teploty m\u00e9dia, jej zvy\u0161ovanie alebo zni\u017eovanie po\u010das procesu mie\u0161ania. Pou\u017e\u00edvaj\u00fa sa n\u00e1dr\u017ee \u0161peci\u00e1lne navrhnut\u00e9 na regul\u00e1ciu teploty. Ke\u010f\u017ee prenos tepla cez steny z\u00e1sobn\u00edka \u010dasto nie je dostato\u010dn\u00fd, musia sa pou\u017ei\u0165 \u010fal\u0161ie prvky v\u00fdmeny tepla, ako s\u00fa mie\u0161acie \u0161pir\u00e1ly, vykurovacie alebo chladiace svie\u010dky a in\u00e9 v\u00fdmenn\u00edky tepla.<\/p>","protected":false},"author":51,"featured_media":10774,"template":"","class_list":["post-10772","grundlagen-guide","type-grundlagen-guide","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ptm-mechatronics.com\/sk\/wp-json\/wp\/v2\/grundlagen-guide\/10772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptm-mechatronics.com\/sk\/wp-json\/wp\/v2\/grundlagen-guide"}],"about":[{"href":"https:\/\/ptm-mechatronics.com\/sk\/wp-json\/wp\/v2\/types\/grundlagen-guide"}],"author":[{"embeddable":true,"href":"https:\/\/ptm-mechatronics.com\/sk\/wp-json\/wp\/v2\/users\/51"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ptm-mechatronics.com\/sk\/wp-json\/wp\/v2\/media\/10774"}],"wp:attachment":[{"href":"https:\/\/ptm-mechatronics.com\/sk\/wp-json\/wp\/v2\/media?parent=10772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}