{"id":12333,"date":"2024-10-16T10:07:54","date_gmt":"2024-10-16T08:07:54","guid":{"rendered":"https:\/\/ptm-mechatronics.com\/?page_id=12333"},"modified":"2026-01-21T09:35:46","modified_gmt":"2026-01-21T08:35:46","slug":"branchen","status":"publish","type":"page","link":"https:\/\/ptm-mechatronics.com\/pt\/branchen\/","title":{"rendered":"Ind\u00fastrias"},"content":{"rendered":"<div class=\"banner has-hover has-parallax\" id=\"banner-2128873395\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-3\" data-parallax-container=\".banner\" data-parallax-background>\n            <img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1068\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Getraenkeproduktion-1.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1955800934\" class=\"text-box banner-layer x50 md-x95 lg-x95 y50 md-y50 lg-y50 res-text\">\n              <div data-parallax=\"4\" data-parallax-fade=\"true\">       <div data-animate=\"fadeInRight\">           <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-1479841104\" class=\"text\">\n\t\t\n<h3 class=\"alt-font\"><span style=\"font-size: 75%;\"><em>A higiene \u00e9 uma prioridade m\u00e1xima<\/em><\/span><\/h3>\n<h3 class=\"uppercase\">Alimenta\u00e7\u00e3o e bebidas <\/h3>\n<p>Os nossos agitadores e motores em a\u00e7o inoxid\u00e1vel s\u00e3o extremamente robustos, estanques, seguros em termos de ATEX e resistentes a meios agressivos. Os agitadores da PTM asseguram uma mistura uniforme e reprodut\u00edvel de l\u00edquidos, emuls\u00f5es e outros ingredientes. Foram concebidos de acordo com os nossos conceitos de higiene Hygienic Design Interior e Soft-Edge Design e s\u00e3o, por isso, f\u00e1ceis de limpar; os dep\u00f3sitos de sujidade e os germes n\u00e3o se podem formar em primeiro lugar. As superf\u00edcies electropolidas tornam a aplica\u00e7\u00e3o higi\u00e9nica perfeita. Para al\u00e9m disso, os nossos agitadores e motores est\u00e3o classificados para a mais alta classe de salas limpas ISO 1, de acordo com a norma DIN 14644.<\/p>\n\t\t\n<style>\n#text-1479841104 {\n  line-height: 1.7;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/ptm-mechatronics.com\/pt\/shop\/\" target=\"_blank\" class=\"button white\" rel=\"noopener\" style=\"border-radius:99px;\">\n\t\t<span>Encontrar produtos<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n       <\/div>       <\/div>              \n<style>\n#text-box-1955800934 .text-box-content {\n  background-color: rgba(41, 109, 173, 0.826);\n  border-radius: 20px;\n  font-size: 100%;\n}\n#text-box-1955800934 .text-inner {\n  padding: 10px 10px 20px 10px;\n}\n#text-box-1955800934 {\n  width: 80%;\n}\n@media (min-width:550px) {\n  #text-box-1955800934 {\n    width: 89%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-1955800934 {\n    width: 49%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2128873395 {\n  padding-top: 631px;\n}\n#banner-2128873395 .overlay {\n  background-color: rgba(0, 0, 0, 0.3);\n}\n#banner-2128873395 .banner-bg img {\n  object-position: 68% 24%;\n}\n@media (min-width:550px) {\n  #banner-2128873395 {\n    padding-top: 481px;\n  }\n}\n@media (min-width:850px) {\n  #banner-2128873395 {\n    padding-top: 621px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-1903401479\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1488476557\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1488476557 {\n  width: 60%;\n}\n#text-box-1488476557 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1488476557 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1903401479 {\n  padding-top: 50px;\n  background-color: rgba(41, 109, 173, 0.797);\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover hide-for-small has-parallax\" id=\"banner-1828945325\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-3\" data-parallax-container=\".banner\" data-parallax-background>\n            <img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1140\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Pharma.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1373372998\" class=\"text-box banner-layer x50 md-x10 lg-x10 y50 md-y50 lg-y50 res-text\">\n              <div data-parallax=\"4\" data-parallax-fade=\"true\">       <div data-animate=\"fadeInDown\">           <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"alt-font\"><em>Sala limpa e assepsia<\/em><\/h3>\n<h3 class=\"uppercase\">Ind\u00fastria farmac\u00eautica e cuidados de sa\u00fade<br \/><\/h3>\n<p>A precis\u00e3o, a pureza e a fiabilidade absoluta do processo s\u00e3o essenciais na ind\u00fastria farmac\u00eautica. Os nossos agitadores e solu\u00e7\u00f5es de acionamento s\u00e3o desenvolvidos precisamente para este fim: higi\u00e9nicos, valid\u00e1veis, energeticamente eficientes e fi\u00e1veis - mesmo sob as condi\u00e7\u00f5es mais exigentes. Descubra como a PTM pode apoiar os seus processos farmac\u00eauticos de forma segura e eficiente.<\/p>\n<a href=\"https:\/\/ptm-mechatronics.com\/pt\/branchen\/ruehren-in-der-pharmabranche\/\" target=\"_blank\" class=\"button white\" rel=\"noopener\" style=\"border-radius:99px;\">\n\t\t<span>Saiba mais<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n       <\/div>       <\/div>              \n<style>\n#text-box-1373372998 .text-box-content {\n  background-color: rgba(41, 109, 173, 0.913);\n  border-radius: 20px;\n  font-size: 100%;\n}\n#text-box-1373372998 .text-inner {\n  padding: 10px 10px 20px 10px;\n}\n#text-box-1373372998 {\n  width: 82%;\n}\n@media (min-width:550px) {\n  #text-box-1373372998 {\n    width: 84%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-1373372998 {\n    width: 81%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1828945325 {\n  padding-top: 401px;\n  background-color: rgb(113, 117, 186);\n}\n#banner-1828945325 .banner-bg img {\n  object-position: 75% 29%;\n}\n@media (min-width:850px) {\n  #banner-1828945325 {\n    padding-top: 509px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover show-for-small has-parallax\" id=\"banner-1552511613\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-3\" data-parallax-container=\".banner\" data-parallax-background>\n            <img loading=\"lazy\" decoding=\"async\" width=\"1662\" height=\"2160\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Pharma-Produktion.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-951919304\" class=\"text-box banner-layer x50 md-x10 lg-x10 y50 md-y50 lg-y50 res-text\">\n              <div data-parallax=\"4\" data-parallax-fade=\"true\">       <div data-animate=\"fadeInLeft\">           <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"alt-font\"><em>Sala limpa e assepsia<\/em><\/h3>\n<h3 class=\"uppercase\">Ind\u00fastria farmac\u00eautica e cuidados de sa\u00fade<br \/><\/h3>\n<p>A precis\u00e3o, a pureza e a fiabilidade absoluta do processo s\u00e3o essenciais na ind\u00fastria farmac\u00eautica. Os nossos agitadores e solu\u00e7\u00f5es de acionamento s\u00e3o desenvolvidos precisamente para este fim: higi\u00e9nicos, valid\u00e1veis, energeticamente eficientes e fi\u00e1veis - mesmo sob as condi\u00e7\u00f5es mais exigentes. Descubra como a PTM pode apoiar os seus processos farmac\u00eauticos de forma segura e eficiente.<\/p>\n<p>\u00a0<\/p>\n<a href=\"https:\/\/ptm-mechatronics.com\/pt\/ruehren-in-der-pharmabranche\/\" target=\"_blank\" class=\"button white\" rel=\"noopener\" style=\"border-radius:99px;\">\n\t\t<span>Saiba mais<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n       <\/div>       <\/div>              \n<style>\n#text-box-951919304 .text-box-content {\n  background-color: rgba(41, 109, 173, 0.826);\n  border-radius: 20px;\n  font-size: 100%;\n}\n#text-box-951919304 .text-inner {\n  padding: 10px 10px 20px 10px;\n}\n#text-box-951919304 {\n  width: 93%;\n}\n@media (min-width:550px) {\n  #text-box-951919304 {\n    width: 81%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1552511613 {\n  padding-top: 595px;\n  background-color: rgb(113, 117, 186);\n}\n#banner-1552511613 .banner-bg img {\n  object-position: 48% 48%;\n}\n@media (min-width:550px) {\n  #banner-1552511613 {\n    padding-top: 800px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-712363462\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-2125340988\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-2125340988 {\n  width: 60%;\n}\n#text-box-2125340988 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-2125340988 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-712363462 {\n  padding-top: 50px;\n  background-color: rgba(41, 109, 173, 0.797);\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover has-parallax\" id=\"banner-1288363071\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-3\" data-parallax-container=\".banner\" data-parallax-background>\n            <img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"981\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Pinsel-mit-Pulver-1.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1930946916\" class=\"text-box banner-layer x50 md-x50 lg-x0 y50 md-y50 lg-y50 res-text\">\n              <div data-parallax=\"4\" data-parallax-fade=\"true\">       <div data-animate=\"fadeInLeft\">           <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"alt-font\"><em>Pureza e integridade<\/em><\/h3>\n<h3 class=\"uppercase\">Cosm\u00e9ticos<\/h3>\n<p>O fabrico de produtos cosm\u00e9ticos exige a mais elevada precis\u00e3o, efici\u00eancia e padr\u00f5es de higiene. Os motores pneum\u00e1ticos e agitadores PTM s\u00e3o especialmente concebidos para satisfazer estes requisitos. Com o nosso princ\u00edpio de pist\u00e3o radial economizador de energia, os nossos motores oferecem o m\u00e1ximo desempenho com o m\u00ednimo consumo de ar - ideal para utiliza\u00e7\u00e3o em ambientes de produ\u00e7\u00e3o sens\u00edveis.<\/p>\n<p>Os nossos agitadores garantem uma mistura uniforme e reprodut\u00edvel de cremes, lo\u00e7\u00f5es, g\u00e9is ou emuls\u00f5es, mesmo com materiais altamente viscosos. Optimizados para aplica\u00e7\u00f5es em salas limpas, cumprem as mais rigorosas normas de higiene e garantem uma produ\u00e7\u00e3o sem contamina\u00e7\u00e3o.<\/p>\n<p>Gra\u00e7as \u00e0 certifica\u00e7\u00e3o ATEX, as nossas solu\u00e7\u00f5es tamb\u00e9m podem ser utilizadas em \u00e1reas potencialmente explosivas, por exemplo, no processamento de produtos \u00e0 base de \u00e1lcool. Com a PTM, beneficia de solu\u00e7\u00f5es de acionamento duradouras, seguras e eficientes que melhoram os seus processos de forma sustent\u00e1vel.<\/p>\n<p>Escolha PTM - para resultados perfeitos, pureza e efici\u00eancia na ind\u00fastria cosm\u00e9tica!<\/p>\n<a href=\"https:\/\/ptm-mechatronics.com\/pt\/shop\/\" target=\"_blank\" class=\"button white\" rel=\"noopener\" style=\"border-radius:99px;\">\n\t\t<span>Encontrar produtos<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n       <\/div>       <\/div>              \n<style>\n#text-box-1930946916 .text-box-content {\n  background-color: rgba(41, 109, 173, 0.826);\n  border-radius: 20px;\n  font-size: 100%;\n}\n#text-box-1930946916 .text-inner {\n  padding: 10px 10px 20px 10px;\n}\n#text-box-1930946916 {\n  width: 95%;\n}\n@media (min-width:550px) {\n  #text-box-1930946916 {\n    width: 88%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-1930946916 {\n    width: 56%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1288363071 {\n  padding-top: 842px;\n  background-color: rgb(113, 117, 186);\n}\n#banner-1288363071 .banner-bg img {\n  object-position: 100% 100%;\n}\n@media (min-width:550px) {\n  #banner-1288363071 {\n    padding-top: 600px;\n  }\n}\n@media (min-width:850px) {\n  #banner-1288363071 {\n    padding-top: 800px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-1045076156\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-505660921\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-505660921 {\n  width: 60%;\n}\n#text-box-505660921 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-505660921 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1045076156 {\n  padding-top: 50px;\n  background-color: rgba(41, 109, 173, 0.797);\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover has-parallax\" id=\"banner-936958921\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-3\" data-parallax-container=\".banner\" data-parallax-background>\n            <img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"765\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Industrie-Chemieanlage-Rohre.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1164029247\" class=\"text-box banner-layer x50 md-x95 lg-x95 y50 md-y50 lg-y50 res-text\">\n              <div data-parallax=\"4\" data-parallax-fade=\"true\">       <div data-animate=\"fadeInRight\">           <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-2339802766\" class=\"text\">\n\t\t\n<h3 class=\"alt-font\"><span style=\"font-size: 75%;\"><em>ATEX-safe e sala limpa<\/em><\/span><\/h3>\n<h3 class=\"uppercase\">Qu\u00edmica e tecnologia de superf\u00edcies<\/h3>\n<p>Solu\u00e7\u00f5es de acionamento precisas, potentes e seguras s\u00e3o indispens\u00e1veis na tecnologia qu\u00edmica e de superf\u00edcies. Os motores pneum\u00e1ticos e agitadores PTM cumprem estes requisitos na perfei\u00e7\u00e3o. Com o seu princ\u00edpio de pist\u00e3o radial economizador de energia, os nossos motores oferecem uma elevada efici\u00eancia e um desempenho fi\u00e1vel com um consumo de ar m\u00ednimo - mesmo em condi\u00e7\u00f5es exigentes.<\/p>\n\t\t\n<style>\n#text-2339802766 {\n  line-height: 1.7;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/ptm-mechatronics.com\/pt\/branchen\/ruehren-in-der-oberflaechentechnik\/\" target=\"_blank\" class=\"button white\" rel=\"noopener\" style=\"border-radius:99px;\">\n\t\t<span>Saiba mais<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n       <\/div>       <\/div>              \n<style>\n#text-box-1164029247 .text-box-content {\n  background-color: rgba(41, 109, 173, 0.826);\n  border-radius: 20px;\n  font-size: 100%;\n}\n#text-box-1164029247 .text-inner {\n  padding: 10px 10px 20px 10px;\n}\n#text-box-1164029247 {\n  width: 94%;\n}\n@media (min-width:550px) {\n  #text-box-1164029247 {\n    width: 88%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-1164029247 {\n    width: 56%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-936958921 {\n  padding-top: 541px;\n}\n#banner-936958921 .overlay {\n  background-color: rgba(0, 0, 0, 0.3);\n}\n#banner-936958921 .banner-bg img {\n  object-position: 70% 72%;\n}\n@media (min-width:550px) {\n  #banner-936958921 {\n    padding-top: 471px;\n  }\n  #banner-936958921 .overlay {\n    background-color: rgba(41, 109, 173, 0.436);\n  }\n}\n@media (min-width:850px) {\n  #banner-936958921 {\n    padding-top: 531px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-524198293\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-683672734\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-683672734 {\n  width: 60%;\n}\n#text-box-683672734 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-683672734 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-524198293 {\n  padding-top: 50px;\n  background-color: rgba(41, 109, 173, 0.797);\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover has-parallax\" id=\"banner-222664410\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-3\" data-parallax-container=\".banner\" data-parallax-background>\n            <img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1065\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Druckmaschine.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1838182464\" class=\"text-box banner-layer x50 md-x50 lg-x0 y50 md-y50 lg-y50 res-text\">\n              <div data-parallax=\"4\" data-parallax-fade=\"true\">       <div data-animate=\"fadeInLeft\">           <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-2174819183\" class=\"text\">\n\t\t\n<h3 class=\"alt-font\"><span style=\"font-size: 75%;\"><em>Seguran\u00e7a e reprodutibilidade ATEX<\/em><\/span><\/h3>\n<h3 class=\"uppercase\">Embalagem e impress\u00e3o <\/h3>\n<p>Os motores pneum\u00e1ticos e agitadores PTM foram especialmente desenvolvidos para as elevadas exig\u00eancias da ind\u00fastria de embalagem e impress\u00e3o. Com o seu princ\u00edpio de pist\u00e3o radial economizador de energia, oferecem o m\u00e1ximo desempenho com o m\u00ednimo consumo de ar. Os nossos agitadores garantem uma mistura uniforme e reprodut\u00edvel - ideal para tintas, vernizes e adesivos.<\/p>\n\t\t\n<style>\n#text-2174819183 {\n  line-height: 1.7;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/ptm-mechatronics.com\/pt\/branchen\/ruehren-in-verpackungsmittel-und-druck\/\" target=\"_blank\" class=\"button white\" rel=\"noopener\" style=\"border-radius:99px;\">\n\t\t<span>Saiba mais<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n       <\/div>       <\/div>              \n<style>\n#text-box-1838182464 .text-box-content {\n  background-color: rgba(41, 109, 173, 0.826);\n  border-radius: 20px;\n  font-size: 100%;\n}\n#text-box-1838182464 .text-inner {\n  padding: 10px 10px 20px 10px;\n}\n#text-box-1838182464 {\n  width: 91%;\n}\n@media (min-width:550px) {\n  #text-box-1838182464 {\n    width: 89%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-1838182464 {\n    width: 51%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-222664410 {\n  padding-top: 568px;\n  background-color: rgb(113, 117, 186);\n}\n#banner-222664410 .overlay {\n  background-color: rgba(41, 109, 173, 0.366);\n}\n#banner-222664410 .banner-bg img {\n  object-position: 100% 100%;\n}\n@media (min-width:550px) {\n  #banner-222664410 {\n    padding-top: 499px;\n  }\n}\n@media (min-width:850px) {\n  #banner-222664410 {\n    padding-top: 550px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-1214998860\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-2044859511\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-2044859511 {\n  width: 60%;\n}\n#text-box-2044859511 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-2044859511 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1214998860 {\n  padding-top: 50px;\n  background-color: rgba(41, 109, 173, 0.797);\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover has-parallax\" id=\"banner-855655833\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-3\" data-parallax-container=\".banner\" data-parallax-background>\n            <img loading=\"lazy\" decoding=\"async\" width=\"1582\" height=\"1000\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/11\/Automation.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1374596401\" class=\"text-box banner-layer x5 md-x95 lg-x95 y50 md-y50 lg-y50 res-text\">\n              <div data-parallax=\"4\" data-parallax-fade=\"true\">       <div data-animate=\"fadeInRight\">           <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-426414584\" class=\"text\">\n\t\t\n<h3 class=\"alt-font\"><span style=\"font-size: 75%;\"><em>Eficiente e potente<\/em><\/span><\/h3>\n<p>&nbsp;<\/p>\n<h3 class=\"uppercase\"><strong>Engenharia mec\u00e2nica e de instala\u00e7\u00f5es<br \/>\n<\/strong><\/h3>\n<p>A PTM mechatronics oferece motores pneum\u00e1ticos e agitadores altamente especializados em engenharia mec\u00e2nica que impressionam pela sua efici\u00eancia, robustez e flexibilidade. Os nossos motores pneum\u00e1ticos baseiam-se no princ\u00edpio do pist\u00e3o radial, que assegura um bin\u00e1rio elevado e uma elevada efici\u00eancia, apesar do baixo consumo de ar. S\u00e3o compactos, silenciosos e podem ser carregados at\u00e9 \u00e0 paragem, o que os torna ideais para uma vasta gama de aplica\u00e7\u00f5es industriais.<\/p>\n<p>Os nossos agitadores s\u00e3o concebidos para diferentes tamanhos de contentores e podem ser personalizados. Caracterizam-se por accionamentos energeticamente eficientes, parametriza\u00e7\u00e3o simples e uma longa vida \u00fatil. Tamb\u00e9m oferecemos modelos com certifica\u00e7\u00e3o ATEX para utiliza\u00e7\u00e3o em atmosferas potencialmente explosivas.<\/p>\n<p>Com a PTM mecatr\u00f3nica, pode confiar na qualidade e na inova\u00e7\u00e3o.<br \/>\n\t\t\n<style>\n#text-426414584 {\n  line-height: 1.7;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/ptm-mechatronics.com\/pt\/shop\/\" target=\"_blank\" class=\"button white\" rel=\"noopener\" style=\"border-radius:99px;\">\n\t\t<span>Encontrar produtos<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n       <\/div>       <\/div>              \n<style>\n#text-box-1374596401 .text-box-content {\n  background-color: rgba(41, 109, 173, 0.826);\n  border-radius: 20px;\n  font-size: 100%;\n}\n#text-box-1374596401 .text-inner {\n  padding: 10px 10px 20px 10px;\n}\n#text-box-1374596401 {\n  width: 91%;\n}\n@media (min-width:550px) {\n  #text-box-1374596401 {\n    width: 88%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-1374596401 {\n    width: 57%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-855655833 {\n  padding-top: 800px;\n}\n#banner-855655833 .overlay {\n  background-color: rgba(0, 0, 0, 0.3);\n}\n#banner-855655833 .banner-bg img {\n  object-position: 68% 24%;\n}\n@media (min-width:550px) {\n  #banner-855655833 {\n    padding-top: 600px;\n  }\n  #banner-855655833 .overlay {\n    background-color: rgba(41, 109, 173, 0.436);\n  }\n}\n@media (min-width:850px) {\n  #banner-855655833 {\n    padding-top: 727px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-1045128509\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1869991867\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1869991867 {\n  width: 60%;\n}\n#text-box-1869991867 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1869991867 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1045128509 {\n  padding-top: 50px;\n  background-color: rgba(41, 109, 173, 0.797);\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover has-parallax\" id=\"banner-952526166\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-3\" data-parallax-container=\".banner\" data-parallax-background>\n            <img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1189\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Weltkugel-auf-Waldboden.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1770565252\" class=\"text-box banner-layer x50 md-x10 lg-x10 y50 md-y50 lg-y50 res-text\">\n              <div data-parallax=\"4\" data-parallax-fade=\"true\">       <div data-animate=\"fadeInDown\">           <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"alt-font\"><em>Energia e sustentabilidade<\/em><\/h3>\n<h3 class=\"uppercase\">Efici\u00eancia e desempenho<\/h3>\n<p>Seja qual for o sector, seja qual for o produto, h\u00e1 um tema que nos preocupa a todos: a gest\u00e3o sustent\u00e1vel. N\u00e3o se trata apenas de poupar energia. Trata-se tamb\u00e9m de manter o desempenho ao mesmo tempo. Porque esta \u00e9 a \u00fanica forma de praticar uma sustentabilidade adequada ao futuro.<\/p>\n<p>Os nossos motores e agitadores s\u00e3o m\u00e1quinas extremamente eficientes. Gra\u00e7as ao seu engenhoso princ\u00edpio de funcionamento, obt\u00e9m-se o m\u00e1ximo desempenho com a menor quantidade de energia. Em resumo: menos consumo de energia, mais pot\u00eancia, menos custos.<\/p>\n<a href=\"https:\/\/ptm-mechatronics.com\/pt\/shop\/\" target=\"_blank\" class=\"button white\" rel=\"noopener\" style=\"border-radius:99px;\">\n\t\t<span>Para os nossos produtos<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n       <\/div>       <\/div>              \n<style>\n#text-box-1770565252 .text-box-content {\n  background-color: rgba(41, 109, 173, 0.826);\n  border-radius: 20px;\n  font-size: 100%;\n}\n#text-box-1770565252 .text-inner {\n  padding: 10px 10px 20px 10px;\n}\n#text-box-1770565252 {\n  width: 95%;\n}\n@media (min-width:550px) {\n  #text-box-1770565252 {\n    width: 81%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-952526166 {\n  padding-top: 537px;\n  background-color: rgb(113, 117, 186);\n}\n#banner-952526166 .overlay {\n  background-color: rgba(41, 109, 173, 0.483);\n}\n#banner-952526166 .banner-bg img {\n  object-position: 100% 100%;\n}\n@media (min-width:550px) {\n  #banner-952526166 {\n    padding-top: 477px;\n  }\n}\n@media (min-width:850px) {\n  #banner-952526166 {\n    padding-top: 563px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t<section class=\"section st-kontakt pt-60 pb-60 col-pb-0\" id=\"section_1172796004\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"444\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/BG_kontakt.png\" class=\"bg attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n<div class=\"row\"  id=\"row-761567099\">\r\n\r\n\n\t<div id=\"col-1467579397\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div id=\"text-434540325\" class=\"text\">\n\t\t\r\n\r\n<h3>Contacto e consultoria<\/h3>\r\n<p>Deseja obter conselhos sobre os nossos produtos? Os nossos especialistas ter\u00e3o todo o prazer em responder ao seu pedido:<\/p>\r\n<h4><a href=\"mailto:info@ptm-mechatronics.com\">info@ptm-mechatronics.com<\/a><br \/>\r\n<a href=\"tel:+498134257970\">+49 8134 \/ 25 797 0<\/a><\/h4>\r\n\t\t\n<style>\n#text-434540325 {\n  color: rgb(255, 255, 255);\n}\n#text-434540325 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1172796004 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n#section_1172796004 .section-bg img {\n  object-position: 84% 53%;\n}\n<\/style>\n\t<\/section>\n\t\r\n\n\t<section class=\"section pb-60 pt-60 besuchen\" id=\"section_1582820137\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n<div class=\"row align-center\"  id=\"row-1677664792\">\r\n\r\n\n\t<div id=\"col-1514901220\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div id=\"text-253116508\" class=\"text title-box\">\n\t\t\r\n\r\n<h3>Tamb\u00e9m pode visitar-nos em<\/h3>\r\n\t\t\n<style>\n#text-253116508 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n<div class=\"row align-middle align-center\" style=\"max-width:605px\" id=\"row-1042820519\">\r\n\r\n\n\t<div id=\"col-17780962\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1730399774\">\n\t\t<a class=\"\" href=\"https:\/\/www.linkedin.com\/company\/68597546\/\" target=\"_blank\" rel=\"noopener\">\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"209\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/PTM-mechatronics-bei-LinkedIn-480x209-1.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/PTM-mechatronics-bei-LinkedIn-480x209-1.png 480w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/PTM-mechatronics-bei-LinkedIn-480x209-1-300x131.png 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/PTM-mechatronics-bei-LinkedIn-480x209-1-100x44.png 100w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/PTM-mechatronics-bei-LinkedIn-480x209-1-447x195.png 447w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1730399774 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1715453360\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1863706258\">\n\t\t<a class=\"\" href=\"https:\/\/www.xing.com\/pages\/ptm-mechatronics-gmbh\" target=\"_blank\" rel=\"noopener\">\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"130\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Xing-1-e1530203231869-300x130-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Xing-1-e1530203231869-300x130-1.jpg 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Xing-1-e1530203231869-300x130-1-100x43.jpg 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1863706258 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1735467315\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_635879507\">\n\t\t<a class=\"\" href=\"https:\/\/www.youtube.com\/@ptmmechatronicsgmbh806\" target=\"_blank\" rel=\"noopener\">\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"133\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Youtube-1-e1530203212402-300x133-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Youtube-1-e1530203212402-300x133-1.jpg 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Youtube-1-e1530203212402-300x133-1-100x44.jpg 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_635879507 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1582820137 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":10812,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-12333","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ptm-mechatronics.com\/pt\/wp-json\/wp\/v2\/pages\/12333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptm-mechatronics.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ptm-mechatronics.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ptm-mechatronics.com\/pt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ptm-mechatronics.com\/pt\/wp-json\/wp\/v2\/comments?post=12333"}],"version-history":[{"count":47,"href":"https:\/\/ptm-mechatronics.com\/pt\/wp-json\/wp\/v2\/pages\/12333\/revisions"}],"predecessor-version":[{"id":15975,"href":"https:\/\/ptm-mechatronics.com\/pt\/wp-json\/wp\/v2\/pages\/12333\/revisions\/15975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ptm-mechatronics.com\/pt\/wp-json\/wp\/v2\/media\/10812"}],"wp:attachment":[{"href":"https:\/\/ptm-mechatronics.com\/pt\/wp-json\/wp\/v2\/media?parent=12333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}