{"id":10772,"date":"2024-09-09T04:05:22","date_gmt":"2024-09-09T02:05:22","guid":{"rendered":"https:\/\/shop.ptm-mechatronics.com\/stage\/?post_type=grundlagen-guide&#038;p=10772"},"modified":"2024-10-07T09:10:36","modified_gmt":"2024-10-07T07:10:36","slug":"waermeuebertragung","status":"publish","type":"grundlagen-guide","link":"https:\/\/ptm-mechatronics.com\/pt\/grundlagen-guide\/waermeuebertragung\/","title":{"rendered":"Transfer\u00eancia de calor"},"content":{"rendered":"<div class=\"row\"  id=\"row-138546291\">\n\n\t<div id=\"col-3813134\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>A transfer\u00eancia de calor consiste em manter constante a temperatura do meio, aumentando-a ou diminuindo-a durante um processo de agita\u00e7\u00e3o. S\u00e3o utilizados tanques especialmente concebidos para o controlo da temperatura. Uma vez que a transfer\u00eancia de calor atrav\u00e9s da parede do tanque n\u00e3o \u00e9 frequentemente suficiente, devem ser instalados no tanque agitador elementos adicionais de troca de calor, tais como serpentinas de agita\u00e7\u00e3o, velas de aquecimento ou arrefecimento e outros modelos especiais. O pr\u00f3prio agitador e a estrutura devem tamb\u00e9m ser concebidos para se adaptarem ao processo de transfer\u00eancia de calor e serem capazes de suportar as temperaturas.<\/p>\n<p>Os agitadores para a transfer\u00eancia de calor s\u00e3o, por isso, muitas vezes personalizados para satisfazer os requisitos individuais da mistura e para obter o melhor resultado. Os agitadores PTM podem ser projectados para temperaturas at\u00e9 300\u00b0C. A pedido, podemos tamb\u00e9m conceber e construir o seu sistema completo com componentes harmonizados.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1515649243\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1161476103\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"785\" height=\"585\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/09\/Agitator-with-special-flange-for-temperature-control-middle-position-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/09\/Agitator-with-special-flange-for-temperature-control-middle-position-1.jpg 785w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/09\/Agitator-with-special-flange-for-temperature-control-middle-position-1-300x224.jpg 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/09\/Agitator-with-special-flange-for-temperature-control-middle-position-1-768x572.jpg 768w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/09\/Agitator-with-special-flange-for-temperature-control-middle-position-1-100x75.jpg 100w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/09\/Agitator-with-special-flange-for-temperature-control-middle-position-1-447x333.jpg 447w\" sizes=\"auto, (max-width: 785px) 100vw, 785px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1161476103 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A transfer\u00eancia de calor consiste em manter constante a temperatura do meio, aumentando-a ou diminuindo-a durante um processo de agita\u00e7\u00e3o. S\u00e3o utilizados tanques especialmente concebidos para o controlo da temperatura. Uma vez que a transfer\u00eancia de calor atrav\u00e9s da parede do tanque n\u00e3o \u00e9 frequentemente suficiente, devem ser utilizados elementos adicionais de troca de calor, tais como serpentinas de agita\u00e7\u00e3o, velas de aquecimento ou arrefecimento e outros permutadores de calor.<\/p>","protected":false},"author":51,"featured_media":10774,"template":"","class_list":["post-10772","grundlagen-guide","type-grundlagen-guide","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ptm-mechatronics.com\/pt\/wp-json\/wp\/v2\/grundlagen-guide\/10772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptm-mechatronics.com\/pt\/wp-json\/wp\/v2\/grundlagen-guide"}],"about":[{"href":"https:\/\/ptm-mechatronics.com\/pt\/wp-json\/wp\/v2\/types\/grundlagen-guide"}],"author":[{"embeddable":true,"href":"https:\/\/ptm-mechatronics.com\/pt\/wp-json\/wp\/v2\/users\/51"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ptm-mechatronics.com\/pt\/wp-json\/wp\/v2\/media\/10774"}],"wp:attachment":[{"href":"https:\/\/ptm-mechatronics.com\/pt\/wp-json\/wp\/v2\/media?parent=10772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}