{"id":11414,"date":"2024-09-11T10:38:09","date_gmt":"2024-09-11T08:38:09","guid":{"rendered":"https:\/\/shop.ptm-mechatronics.com\/stage\/?p=11414"},"modified":"2025-01-27T12:12:51","modified_gmt":"2025-01-27T11:12:51","slug":"basics-fuer-den-ruehrwerkskauf","status":"publish","type":"post","link":"https:\/\/ptm-mechatronics.com\/it\/basics-fuer-den-ruehrwerkskauf\/","title":{"rendered":"Nozioni di base per l'acquisto di un agitatore"},"content":{"rendered":"<div class=\"banner has-hover banner-page-top\" id=\"banner-1135561489\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"801\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Gruppenfoto-Faesser-eco-Cap-eco-Traverse-Schraegtraverse-eco-Drive-eco-TopDrive.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-258020769\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-258020769 {\n  width: 60%;\n}\n#text-box-258020769 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1135561489 {\n  padding-top: 500px;\n}\n<\/style>\n  <\/div>\n\n\n\n\t<section class=\"section\" id=\"section_607182055\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1248543866\">\n\n\t<div id=\"col-1819070452\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h1>Nozioni di base per l'acquisto di un agitatore<\/h1>\n<p>Avete bisogno di un agitatore? Ma non siete sicuri di come affrontare il compito? Allora siete nel posto giusto.<\/p>\n<p>La scelta di un agitatore adatto pu\u00f2 essere facilmente determinata con l'aiuto di alcuni criteri. Una volta definiti questi criteri, la scelta dell'agitatore e dei componenti giusti \u00e8 solo una questione di diligenza. Grazie a questi pochi dettagli, possiamo offrirvi in breve tempo un agitatore perfettamente personalizzato per il vostro compito di miscelazione. E potrete essere certi di ottenere un risultato di miscelazione perfetto. Scoprite subito quali sono questi punti:<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1384661660\">\n\n\t<div id=\"col-1477327717\" class=\"col cl-white col-pb-0 small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-894903294\">\n\n\t<div id=\"col-1689167586\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h5>1. cosa deve essere mescolato?<\/h5>\n<p>Prima cosa importante: quale sostanza deve essere mescolata? Si tratta di sostanze solide come polveri o granuli? Liquidi come acqua, oli, aromi? Oppure si tratta di una miscela di due sostanze diverse, solidi e liquidi o liquidi e gas? Tutto ci\u00f2 influisce principalmente sulla scelta dell'agitatore e sulle prestazioni dell'azionamento dell'agitatore. E ci porta direttamente alla sezione successiva:<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-156657478\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover b-r-10 x md-x lg-x y md-y lg-y\" id=\"image_1260815545\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"357\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Fluessig-Pulvrig-1-480x357-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Fluessig-Pulvrig-1-480x357-1.jpg 480w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Fluessig-Pulvrig-1-480x357-1-300x223.jpg 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Fluessig-Pulvrig-1-480x357-1-100x74.jpg 100w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Fluessig-Pulvrig-1-480x357-1-447x332.jpg 447w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1260815545 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-333201149\">\n\n\t<div id=\"col-818635628\" class=\"col cl-grey cl-white col-pb-0 small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row align-middle\"  id=\"row-1557810526\">\n\n\t<div id=\"col-2103142613\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h5>2. quali sono la viscosit\u00e0 e la densit\u00e0 del materiale da agitare?<\/h5>\n<p>In relazione al punto 1, si pu\u00f2 ora determinare la viscosit\u00e0, cio\u00e8 la viscosit\u00e0 della sostanza da mescolare. Se la viscosit\u00e0 \u00e8 alta, la sostanza \u00e8 pi\u00f9 viscosa, come il miele. Se \u00e8 bassa, la sostanza \u00e8 pi\u00f9 liquida, come l'acqua (<a href=\"https:\/\/ptm-mechatronics.com\/it\/grundlagen-guide\/viskositaet\/\" target=\"_blank\" rel=\"noopener\">Per una spiegazione pi\u00f9 dettagliata, leggete anche il nostro articolo sulla viscosit\u00e0 nella nostra Wiki PTM.<\/a>.). La viscosit\u00e0 ha una forte influenza sulle prestazioni dell'azionamento dell'agitatore da selezionare. Una viscosit\u00e0 pi\u00f9 elevata richiede una coppia maggiore.<\/p>\n<p>Lo stesso vale per la densit\u00e0. In una sostanza agitante possono essere presenti anche sostanze con densit\u00e0 diverse. Ad esempio, quando si aggiungono granuli o polveri ai liquidi. Le sostanze con una densit\u00e0 maggiore, cio\u00e8 il granulato o la polvere, affondano sul fondo. Il processo di miscelazione, cio\u00e8 la distribuzione dei solidi nei liquidi, \u00e8 chiamato\u00a0<a href=\"https:\/\/ptm-mechatronics.com\/it\/grundlagen-guide\/suspendieren\/\" target=\"_blank\" rel=\"noopener\">Sospendere<\/a>. I solidi possono anche avere densit\u00e0 diverse. Il processo di miscelazione \u00e8 chiamato\u00a0<a href=\"https:\/\/ptm-mechatronics.com\/it\/grundlagen-guide\/feststoffmischen\/\" target=\"_blank\" rel=\"noopener\">Miscelazione di solidi<\/a>. Assicuratevi di utilizzare l'agitatore giusto per questi processi. Gli agitatori con elevate forze di taglio, come il disco dissolutore, sono perfetti per rompere i solidi e distribuirli in un liquido. Gli agitatori a spirale garantiscono una miscelazione ottimale dei solidi.<\/p>\n<p>L'insieme dei punti 1 e 2 vi indicher\u00e0 l'attivit\u00e0 di mescolamento che fa al caso vostro. I dettagli sono riportati al punto 3:<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1692390172\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover b-r-10 x md-x lg-x y md-y lg-y\" id=\"image_1607555094\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"358\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Holzboden-Oel-blau-1-480x358-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Holzboden-Oel-blau-1-480x358-1.jpg 480w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Holzboden-Oel-blau-1-480x358-1-300x224.jpg 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Holzboden-Oel-blau-1-480x358-1-100x75.jpg 100w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Holzboden-Oel-blau-1-480x358-1-447x333.jpg 447w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1607555094 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1687532319\">\n\n\t<div id=\"col-1715537107\" class=\"col cl-white col-pb-0 small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row align-middle\"  id=\"row-1103216447\">\n\n\t<div id=\"col-1276929211\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h5>3. qual \u00e8 il compito?<\/h5>\n<p>Le considerazioni precedenti indicano il compito effettivo del processo di miscelazione. Per ottenere una miscelazione efficace sono necessarie forze di taglio elevate e una forte immissione di aria? Oppure il processo di miscelazione deve essere delicato? \u00c8 necessario evitare a tutti i costi l'aspirazione dell'aria?<\/p>\n<p>La tecnologia degli agitatori definisce i vari compiti che un agitatore pu\u00f2 svolgere. Questi possono essere:<br \/><a href=\"https:\/\/ptm-mechatronics.com\/it\/grundlagen-guide\/dispergieren-fluessig-fluessig\/\" target=\"_blank\" rel=\"noopener\">Dispersione liquido-liquido<\/a>,\u00a0<a href=\"https:\/\/ptm-mechatronics.com\/it\/grundlagen-guide\/dispergieren-gas-fluessig\/\" target=\"_blank\" rel=\"noopener\">Dispersione gas-liquido<\/a>,\u00a0<a href=\"https:\/\/ptm-mechatronics.com\/it\/grundlagen-guide\/suspendieren\/\" target=\"_blank\" rel=\"noopener\">Sospendere<\/a>,\u00a0<a href=\"https:\/\/ptm-mechatronics.com\/it\/grundlagen-guide\/homogenisieren\/\" target=\"_blank\" rel=\"noopener\">Omogeneizzare<\/a>,\u00a0<a href=\"https:\/\/ptm-mechatronics.com\/it\/grundlagen-guide\/feststoffmischen\/\" target=\"_blank\" rel=\"noopener\">Miscelazione di solidi<\/a>\u00a0o il\u00a0<a href=\"https:\/\/ptm-mechatronics.com\/it\/grundlagen-guide\/waermeuebertragung\/\" target=\"_blank\" rel=\"noopener\">Trasferimento di calore<\/a>. Leggete i nostri articoli su questo argomento nel nostro\u00a0<a href=\"https:\/\/ptm-mechatronics.com\/it\/wiki\/\" target=\"_blank\" rel=\"noopener\">Wiki PTM<\/a>, in cui vi presentiamo questi processi in dettaglio.<\/p>\n<p>Ognuno di questi processi pone le proprie esigenze specifiche alla\u00a0<a href=\"https:\/\/ptm-mechatronics.com\/it\/grundlagen-guide\/stroemungsarten-beim-ruehrprozess\/\" target=\"_blank\" rel=\"noopener\">Comportamento del flusso<\/a>\u00a0nel serbatoio (laminare o turbolento),\u00a0<a href=\"https:\/\/ptm-mechatronics.com\/it\/grundlagen-guide\/stroemungsprofile-von-ruehrorganen\/\" target=\"_blank\" rel=\"noopener\">Profili di flusso<\/a>\u00a0gli agitatori (trasporto assiale, radiale o tangenziale) e le installazioni o sovrastrutture necessarie, come serpentine di riscaldamento o raffreddamento o deflettori.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-716644651\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover b-r-10 x md-x lg-x y md-y lg-y\" id=\"image_1877705700\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"342\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Farbe-blau-1-480x342-1.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Farbe-blau-1-480x342-1.png 480w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Farbe-blau-1-480x342-1-300x214.png 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Farbe-blau-1-480x342-1-100x71.png 100w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Farbe-blau-1-480x342-1-447x318.png 447w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1877705700 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1120459412\">\n\n\t<div id=\"col-495759703\" class=\"col cl-grey cl-white col-pb-0 small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-1859611295\">\n\n\t<div id=\"col-277664657\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h5>4. Quale quantit\u00e0 deve essere mescolata?<\/h5>\n<p>La quantit\u00e0 di sostanza da mescolare non solo influisce in modo significativo sulle dimensioni dell'agitatore, cio\u00e8 sulle dimensioni dell'albero, dell'elemento agitatore o del supporto. Anche la potenza del motore deve essere adeguata alla quantit\u00e0. Logicamente, la potenza e la coppia sono tanto maggiori quanto pi\u00f9 grandi sono le quantit\u00e0 da agitare.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1986721245\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover b-r-10 x md-x lg-x y md-y lg-y\" id=\"image_1376421214\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"785\" height=\"585\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/ATEX-Ruehrwerke-fuer-IBC-Container-Faesser-Kunststofffaesser-Hubstationen-1-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/ATEX-Ruehrwerke-fuer-IBC-Container-Faesser-Kunststofffaesser-Hubstationen-1-1.jpg 785w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/ATEX-Ruehrwerke-fuer-IBC-Container-Faesser-Kunststofffaesser-Hubstationen-1-1-300x224.jpg 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/ATEX-Ruehrwerke-fuer-IBC-Container-Faesser-Kunststofffaesser-Hubstationen-1-1-768x572.jpg 768w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/ATEX-Ruehrwerke-fuer-IBC-Container-Faesser-Kunststofffaesser-Hubstationen-1-1-100x75.jpg 100w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/ATEX-Ruehrwerke-fuer-IBC-Container-Faesser-Kunststofffaesser-Hubstationen-1-1-447x333.jpg 447w\" sizes=\"auto, (max-width: 785px) 100vw, 785px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1376421214 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1375250164\">\n\n\t<div id=\"col-868719207\" class=\"col cl-white col-pb-0 small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row align-middle\"  id=\"row-1832910725\">\n\n\t<div id=\"col-1241201703\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h5>5. Quali sono i contenitori utilizzati?<\/h5>\n<p>Nella tecnologia degli agitatori si utilizzano spesso contenitori standardizzati. Nel settore degli agitatori di piccole e medie dimensioni, si tratta di solito di tamburi (circa 30 litri), fusti (circa 100-500 litri) o grandi contenitori IBC (circa 600-1.200 litri). Naturalmente, esistono anche sistemi di grandi dimensioni con migliaia di litri, come nel caso del trattamento delle acque reflue. Le dimensioni del contenitore definiscono principalmente la dimensione, la forma e il numero di agitatori e la lunghezza dell'albero dell'agitatore.<\/p>\n<p>Il tipo di contenitore determina anche il design dell'agitatore sul contenitore stesso. Avete bisogno di un\u00a0<a href=\"https:\/\/ptm-mechatronics.com\/it\/categoria-prodotto\/ruehrwerkstechnik\/fassruehrwerke\/?swoof=1&amp;paged=1&amp;really_curr_tax=603-product_cat\" target=\"_blank\" rel=\"noopener\">Traversata o copertura<\/a>? Oppure si pu\u00f2 optare per un comodo\u00a0<a href=\"https:\/\/ptm-mechatronics.com\/it\/categoria-prodotto\/ruehrwerkstechnik\/?swoof=1&amp;pa_typ=stativruehrwerk&amp;paged=1&amp;really_curr_tax=595-product_cat\" target=\"_blank\" rel=\"noopener\">Agitatore a cavalletto<\/a>\u00a0indietro?<\/p>\n<p>Naturalmente, esistono anche contenitori speciali non conformi allo standard, come i contenitori per processi chimici. Questi contenitori hanno aperture specifiche per applicazioni aggiuntive. Spesso vengono utilizzate soluzioni flangiate speciali, tipiche del settore, come le flange DN,\u00a0<a href=\"https:\/\/ptm-mechatronics.com\/it\/grundlagen-guide\/tri-clamp\/\" target=\"_blank\" rel=\"noopener\">TriClamp<\/a>\u00a0o attacco filettato per il latte.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1130369072\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover b-r-10 x md-x lg-x y md-y lg-y\" id=\"image_1153919028\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"785\" height=\"585\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Gruppenfoto-Ruehrwerke-Faesser-Kunststofffaesser-Hubstation-Deckel-Traverse-Schraegtraverse-web-1-2.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Gruppenfoto-Ruehrwerke-Faesser-Kunststofffaesser-Hubstation-Deckel-Traverse-Schraegtraverse-web-1-2.jpg 785w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Gruppenfoto-Ruehrwerke-Faesser-Kunststofffaesser-Hubstation-Deckel-Traverse-Schraegtraverse-web-1-2-300x224.jpg 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Gruppenfoto-Ruehrwerke-Faesser-Kunststofffaesser-Hubstation-Deckel-Traverse-Schraegtraverse-web-1-2-768x572.jpg 768w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Gruppenfoto-Ruehrwerke-Faesser-Kunststofffaesser-Hubstation-Deckel-Traverse-Schraegtraverse-web-1-2-100x75.jpg 100w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Gruppenfoto-Ruehrwerke-Faesser-Kunststofffaesser-Hubstation-Deckel-Traverse-Schraegtraverse-web-1-2-447x333.jpg 447w\" sizes=\"auto, (max-width: 785px) 100vw, 785px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1153919028 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-691146252\">\n\n\t<div id=\"col-1680259085\" class=\"col cl-grey cl-white col-pb-0 small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row align-middle\"  id=\"row-1566532316\">\n\n\t<div id=\"col-654860313\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h5>6. Esiste un ambiente speciale o ci sono requisiti particolari?<\/h5>\n<p>Il processo, la miscela o l'ambiente possono far s\u00ec che il processo di miscelazione sia soggetto a requisiti speciali. Ad esempio, durante l'agitazione possono essere prodotti gas esplosivi, come spesso accade nell'industria chimica. In questo caso, gli agitatori devono\u00a0<a href=\"https:\/\/ptm-mechatronics.com\/it\/grundlagen-guide\/atex\/\" target=\"_blank\" rel=\"noopener\">ATEX<\/a>-certificati. Alcuni processi sono critici dal punto di vista igienico, ad esempio nell'industria alimentare, cosmetica o farmaceutica, e richiedono l'ambiente sterile di una camera bianca e la possibilit\u00e0 di sterilizzare i componenti. \u00c8 necessario rispettare le linee guida per la conformit\u00e0 farmaceutica e alimentare. Il\u00a0<a href=\"https:\/\/ptm-mechatronics.com\/it\/grundlagen-guide\/ip67-und-ip68\/\" target=\"_blank\" rel=\"noopener\">Grado di protezione IP67<\/a> gioca un ruolo importante nelle applicazioni in ambienti umidi o che richiedono una frequente pulizia a umido.<\/p>\n<p>Ci\u00f2 influenza a sua volta il materiale e le propriet\u00e0 degli agitatori stessi, nonch\u00e9 i componenti che entrano in contatto con i fluidi, come l'albero dell'agitatore, l'elemento agitatore e il contenitore. Ad esempio, gli agitatori certificati ATEX sono utilizzati per requisiti speciali, mentre per le applicazioni igieniche si utilizzano materiali robusti.\u00a0<a href=\"https:\/\/ptm-mechatronics.com\/it\/categoria-prodotto\/ruehrwerkstechnik\/?swoof=1&amp;pa_reinraumklassifizierung=iso1-nach-din14644&amp;paged=1&amp;really_curr_tax=595-product_cat\" target=\"_blank\" rel=\"noopener\">Acciaio inox<\/a>. In alcuni casi, sono necessarie strutture aggiuntive per creare l'ambiente speciale, come i sistemi di estrazione.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-802859475\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover b-r-10 x md-x lg-x y md-y lg-y\" id=\"image_315719201\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"572\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Automation-1-768x572-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Automation-1-768x572-1.jpg 768w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Automation-1-768x572-1-300x223.jpg 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Automation-1-768x572-1-100x74.jpg 100w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Automation-1-768x572-1-447x333.jpg 447w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_315719201 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1102915837\">\n\n\t<div id=\"col-393235983\" class=\"col cl-white col-pb-0 small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-1021754911\">\n\n\t<div id=\"col-1394870461\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h5>7. componenti a monte e a valle<\/h5>\n<p>Le applicazioni di agitazione sono completate da componenti a monte e a valle, ad esempio per l'aggiunta di sostanze o la rimozione della miscela. Questi includono dispositivi di dosaggio, sensori di misura, sistemi di riempimento, bilance, griglie di raccolta, ecc. Per informazioni dettagliate in merito, consultare il nostro\u00a0<a href=\"https:\/\/ptm-mechatronics.com\/it\/sonderloesungen\/\">Ingegneria degli impianti<\/a>.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1175905470\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover b-r-10 x md-x lg-x y md-y lg-y\" id=\"image_1178727049\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"358\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Dosiertechnik-1-480x358-1.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Dosiertechnik-1-480x358-1.png 480w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Dosiertechnik-1-480x358-1-300x224.png 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Dosiertechnik-1-480x358-1-100x75.png 100w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Dosiertechnik-1-480x358-1-447x333.png 447w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1178727049 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1061173866\">\n\n\t<div id=\"col-1130934253\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Dopo aver riflettuto su questi criteri, siete gi\u00e0 molto vicini al vostro agitatore.<\/p>\n<p>Naturalmente, saremo lieti di esaminare personalmente questi criteri con voi. L'importante \u00e8 che alla fine si ottenga il risultato di miscelazione perfetto.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_607182055 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section st-kontakt pt-60 pb-60 col-pb-0\" id=\"section_987269157\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"444\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/BG_kontakt.png\" class=\"bg attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n<div class=\"row\"  id=\"row-1124981373\">\r\n\r\n\n\t<div id=\"col-1795526224\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div id=\"text-4152405554\" class=\"text\">\n\t\t\r\n\r\n<h3>Contatto e consulenza<\/h3>\r\n<p>Desiderate una consulenza sui nostri prodotti? I nostri esperti saranno lieti di rispondere alle vostre richieste:<\/p>\r\n<h4><a href=\"mailto:info@ptm-mechatronics.com\">info@ptm-mechatronics.com<\/a><br \/>\r\n<a href=\"tel:+498134257970\">+49 8134 \/ 25 797 0<\/a><\/h4>\r\n\t\t\n<style>\n#text-4152405554 {\n  color: rgb(255, 255, 255);\n}\n#text-4152405554 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_987269157 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n#section_987269157 .section-bg img {\n  object-position: 84% 53%;\n}\n<\/style>\n\t<\/section>\n\t\r\n\n\t<section class=\"section pb-60 pt-60 besuchen\" id=\"section_1414334371\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n<div class=\"row align-center\"  id=\"row-481884089\">\r\n\r\n\n\t<div id=\"col-376293142\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div id=\"text-3829448720\" class=\"text title-box\">\n\t\t\r\n\r\n<h3>Potete anche visitarci all'indirizzo<\/h3>\r\n\t\t\n<style>\n#text-3829448720 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n<div class=\"row align-middle align-center\" style=\"max-width:605px\" id=\"row-1319598701\">\r\n\r\n\n\t<div id=\"col-1932542787\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1721434584\">\n\t\t<a class=\"\" href=\"https:\/\/www.linkedin.com\/company\/68597546\/\" target=\"_blank\" rel=\"noopener\">\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"209\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/PTM-mechatronics-bei-LinkedIn-480x209-1.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/PTM-mechatronics-bei-LinkedIn-480x209-1.png 480w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/PTM-mechatronics-bei-LinkedIn-480x209-1-300x131.png 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/PTM-mechatronics-bei-LinkedIn-480x209-1-100x44.png 100w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/PTM-mechatronics-bei-LinkedIn-480x209-1-447x195.png 447w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1721434584 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1709112256\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1001322176\">\n\t\t<a class=\"\" href=\"https:\/\/www.xing.com\/pages\/ptm-mechatronics-gmbh\" target=\"_blank\" rel=\"noopener\">\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"130\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Xing-1-e1530203231869-300x130-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Xing-1-e1530203231869-300x130-1.jpg 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Xing-1-e1530203231869-300x130-1-100x43.jpg 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1001322176 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1312177299\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1042964805\">\n\t\t<a class=\"\" href=\"https:\/\/www.youtube.com\/@ptmmechatronicsgmbh806\" target=\"_blank\" rel=\"noopener\">\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"133\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Youtube-1-e1530203212402-300x133-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Youtube-1-e1530203212402-300x133-1.jpg 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Youtube-1-e1530203212402-300x133-1-100x44.jpg 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1042964805 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1414334371 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"<p>Avete bisogno di un agitatore? Ma non siete sicuri di come affrontare il compito? Allora siete nel posto giusto.<\/p>\n<p>La scelta di un agitatore adatto pu\u00f2 essere facilmente determinata con l'aiuto di alcuni criteri. Una volta definiti questi criteri, la scelta dell'agitatore e dei componenti giusti \u00e8 solo una questione di diligenza. Grazie a questi pochi dettagli, possiamo offrirvi in breve tempo un agitatore perfettamente personalizzato per il vostro compito di miscelazione. E potrete essere certi di ottenere un risultato di miscelazione perfetto. Scoprite subito quali sono questi punti:<\/p>","protected":false},"author":51,"featured_media":12002,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2243,2363],"tags":[2434,2435,2436,2437,2217,2438,2439,2440,2441,2442,2443],"class_list":["post-11414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ruehrwerkstechnik","category-wissensbeitrag","tag-dispergieren","tag-homogenisieren","tag-kauf","tag-ruehrtechnik","tag-ruehrwerk","tag-ruehrwerkskauf","tag-stroemungsart","tag-stroemungsprofil","tag-suspendieren","tag-viskositaet","tag-waermetausch"],"acf":[],"_links":{"self":[{"href":"https:\/\/ptm-mechatronics.com\/it\/wp-json\/wp\/v2\/posts\/11414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptm-mechatronics.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ptm-mechatronics.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ptm-mechatronics.com\/it\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/ptm-mechatronics.com\/it\/wp-json\/wp\/v2\/comments?post=11414"}],"version-history":[{"count":2,"href":"https:\/\/ptm-mechatronics.com\/it\/wp-json\/wp\/v2\/posts\/11414\/revisions"}],"predecessor-version":[{"id":12879,"href":"https:\/\/ptm-mechatronics.com\/it\/wp-json\/wp\/v2\/posts\/11414\/revisions\/12879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ptm-mechatronics.com\/it\/wp-json\/wp\/v2\/media\/12002"}],"wp:attachment":[{"href":"https:\/\/ptm-mechatronics.com\/it\/wp-json\/wp\/v2\/media?parent=11414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ptm-mechatronics.com\/it\/wp-json\/wp\/v2\/categories?post=11414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ptm-mechatronics.com\/it\/wp-json\/wp\/v2\/tags?post=11414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}