{"id":12303,"date":"2024-10-10T11:56:50","date_gmt":"2024-10-10T09:56:50","guid":{"rendered":"https:\/\/ptm-mechatronics.com\/?page_id=12303"},"modified":"2025-04-07T10:48:51","modified_gmt":"2025-04-07T08:48:51","slug":"service","status":"publish","type":"page","link":"https:\/\/ptm-mechatronics.com\/fr\/service\/","title":{"rendered":"Service"},"content":{"rendered":"<div class=\"slider-wrapper relative hide-for-small\" id=\"slider-662634330\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": false,            \"wrapAround\": true,            \"autoPlay\": 6000,            \"pauseAutoPlayOnHover\" : true,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": true,            \"rightToLeft\": false,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n  <div class=\"banner has-hover\" id=\"banner-584420315\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1484\" height=\"585\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Kolben-und-Motor-Hintergrund.jpg\" class=\"bg attachment-2048x2048 size-2048x2048\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-336025034\" class=\"text-box banner-layer x95 md-x95 lg-x100 y90 md-y90 lg-y85 res-text\">\n                     <div data-animate=\"flipInY\">           <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"alt-font\">Que pouvons-nous faire pour vous ?<\/h3>\n<div class=\"is-divider divider clearfix\" style=\"margin-top:3px;margin-bottom:3px;\"><\/div>\n<h1 class=\"h-large uppercase\"><span style=\"font-size: 160%;\">Service<\/span><\/h1>\n<div class=\"is-divider divider clearfix\" ><\/div>\n              <\/div>\n           <\/div>\n       <\/div>                     \n<style>\n#text-box-336025034 {\n  margin: 185px 0px 0px 290px;\n  width: 100%;\n}\n#text-box-336025034 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-336025034 {\n    width: 60%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-336025034 {\n    width: 59%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-584420315 {\n  padding-top: 400px;\n}\n#banner-584420315 .overlay {\n  background-color: rgba(0, 0, 0, 0.384);\n}\n#banner-584420315 .banner-bg img {\n  object-position: 58% 63%;\n}\n@media (min-width:850px) {\n  #banner-584420315 {\n    padding-top: 600px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n<div class=\"slider-wrapper relative show-for-small\" id=\"slider-865491428\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": false,            \"wrapAround\": true,            \"autoPlay\": 6000,            \"pauseAutoPlayOnHover\" : true,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": true,            \"rightToLeft\": false,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n  <div class=\"banner has-hover\" id=\"banner-1264591224\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"785\" height=\"585\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Kolben-und-Motor-Hintergrund-iphone.jpg\" class=\"bg attachment-large size-large\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-252915294\" class=\"text-box banner-layer x50 md-x50 lg-x100 y90 md-y75 lg-y85 res-text\">\n                     <div data-animate=\"flipInY\">           <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"alt-font\">Que pouvons-nous faire pour vous ?<\/h3>\n\t<div id=\"gap-1059561796\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1059561796 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:3px;margin-bottom:3px;\"><\/div>\n<h1 class=\"h-large uppercase\"><span style=\"font-size: 160%;\">Service<\/span><\/h1>\n<div class=\"is-divider divider clearfix\" ><\/div>\n              <\/div>\n           <\/div>\n       <\/div>                     \n<style>\n#text-box-252915294 {\n  width: 100%;\n}\n#text-box-252915294 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-252915294 {\n    width: 98%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-252915294 {\n    width: 59%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1264591224 {\n  padding-top: 300px;\n}\n#banner-1264591224 .overlay {\n  background-color: rgba(0, 0, 0, 0.419);\n}\n#banner-1264591224 .banner-bg img {\n  object-position: 58% 63%;\n}\n@media (min-width:550px) {\n  #banner-1264591224 {\n    padding-top: 600px;\n  }\n  #banner-1264591224 .overlay {\n    background-color: rgba(0, 0, 0, 0.384);\n  }\n}\n<\/style>\n  <\/div>\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 row-small slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <\/div>\n\t<div id=\"gap-953634959\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-953634959 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row row-divided hide-for-small\"  id=\"row-1032499855\">\n\n\t<div id=\"col-1583732721\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 186px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:2px;color:rgb(182, 182, 182);\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"240\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Videokonferenz-Icon.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Videokonferenz-Icon.png 240w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Videokonferenz-Icon-150x150.png 150w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Videokonferenz-Icon-100x100.png 100w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Contact t\u00e9l\u00e9phonique rapide<\/h5>\t\t\t\t\t\t\n<p>Notre service client\u00e8le se tient \u00e0 votre disposition par t\u00e9l\u00e9phone pendant les heures de bureau. Acc\u00e9der au contact t\u00e9l\u00e9phonique <a href=\"tel:+498134257970\">ici<\/a>.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-924086172\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 186px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:2px;color:rgb(182, 182, 182);\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"240\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0024_Ergebnis.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0024_Ergebnis.png 240w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0024_Ergebnis-150x150.png 150w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0024_Ergebnis-100x100.png 100w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">R\u00e9server un rendez-vous en ligne<\/h5>\t\t\t\t\t\t\n<p>R\u00e9servez simplement un rendez-vous de conseil avec l'un de nos techniciens d'application. Pour r\u00e9server un rendez-vous, cliquez ici <a href=\"https:\/\/calendly.com\/thomas-schmalz\/30min\" target=\"_blank\" rel=\"noopener\">ici<\/a>.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-987557064\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 186px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:2px;color:rgb(182, 182, 182);\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"240\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0022_Beratung.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0022_Beratung.png 240w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0022_Beratung-150x150.png 150w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0022_Beratung-100x100.png 100w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Chat en ligne<\/h5>\t\t\t\t\t\t\n<p>Pour les questions br\u00e8ves ou urgentes, notre fonction de chat est \u00e0 votre disposition pendant les heures de bureau. Vous la trouverez en bas \u00e0 gauche de l'\u00e9cran.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-divided show-for-small\"  id=\"row-578560429\">\n\n\t<div id=\"col-915444966\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 186px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:2px;color:rgb(182, 182, 182);\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"240\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Videokonferenz-Icon.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Videokonferenz-Icon.png 240w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Videokonferenz-Icon-150x150.png 150w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Videokonferenz-Icon-100x100.png 100w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Contact t\u00e9l\u00e9phonique rapide<\/h5>\t\t\t\t\t\t\n<p>Notre service client\u00e8le se tient \u00e0 votre disposition par t\u00e9l\u00e9phone. Acc\u00e9der au contact t\u00e9l\u00e9phonique <a href=\"tel:+498134257970\">ici<\/a>.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1451216625\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 186px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:2px;color:rgb(182, 182, 182);\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"240\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0024_Ergebnis.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0024_Ergebnis.png 240w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0024_Ergebnis-150x150.png 150w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0024_Ergebnis-100x100.png 100w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">R\u00e9server un rendez-vous en ligne<\/h5>\t\t\t\t\t\t\n<p>R\u00e9server <a href=\"https:\/\/calendly.com\/thomas-schmalz\/30min\" target=\"_blank\" rel=\"noopener\">ici<\/a> un rendez-vous de conseil avec l'un de nos techniciens d'application.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-divided show-for-small\"  id=\"row-2043483833\">\n\n\t<div id=\"col-1557727244\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 186px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:2px;color:rgb(182, 182, 182);\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"240\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0022_Beratung.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0022_Beratung.png 240w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0022_Beratung-150x150.png 150w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0022_Beratung-100x100.png 100w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Chat en ligne<\/h5>\t\t\t\t\t\t\n<p>Pour les questions br\u00e8ves ou urgentes : notre fonction de chat. Vous la trouverez en bas \u00e0 gauche de l'\u00e9cran.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1408856642\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 186px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:2px;color:rgb(182, 182, 182);\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"240\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0026_Ex.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0026_Ex.png 240w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0026_Ex-150x150.png 150w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0026_Ex-100x100.png 100w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Essai ATEX<\/h5>\t\t\t\t\t\t\n<p>R\u00e9servez notre service de maintenance <a href=\"tel:+498134257970\">ici<\/a> et nous veillons \u00e0 ce que votre installation reste s\u00e9curis\u00e9e ATEX.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-352462357\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-352462357 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row row-divided hide-for-small\"  id=\"row-377937502\">\n\n\t<div id=\"col-724763020\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 186px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:2px;color:rgb(182, 182, 182);\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"240\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0026_Ex.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0026_Ex.png 240w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0026_Ex-150x150.png 150w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0026_Ex-100x100.png 100w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Service d'essai ATEX<\/h5>\t\t\t\t\t\t\n<p>R\u00e9servez notre service de maintenance sur place <a href=\"tel:+498134257970\">ici<\/a> et nous veillons \u00e0 ce que votre installation soit s\u00e9curis\u00e9e ATEX et reste toujours \u00e0 la pointe de la technologie.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1954538543\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 186px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:2px;color:rgb(182, 182, 182);\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"240\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0005_Professionalita\u2560et.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0005_Professionalita\u2560et.png 240w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0005_Professionalita\u2560et-150x150.png 150w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0005_Professionalita\u2560et-100x100.png 100w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Vid\u00e9os \"Comment faire\"<\/h5>\t\t\t\t\t\t\n<p>Nos vid\u00e9os \"how-to-vid\u00e9o\" expliquent le montage, l'entretien ou l'utilisation de nos produits. <a href=\"https:\/\/www.youtube.com\/channel\/UCNkHDgEMLMyu8U7_NrlRhhQ\" target=\"_blank\" rel=\"noopener\">Ici<\/a> pour acc\u00e9der \u00e0 la cha\u00eene YouTube PTM.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-194248438\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 186px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:2px;color:rgb(182, 182, 182);\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"240\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0003_Robust.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0003_Robust.png 240w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0003_Robust-150x150.png 150w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0003_Robust-100x100.png 100w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">R\u00e9paration<\/h5>\t\t\t\t\t\t\n<p>Nous r\u00e9parons nos entra\u00eenements dans les 24 heures. Pour une livraison avant 12 heures, votre entra\u00eenement vous sera m\u00eame retourn\u00e9 le jour m\u00eame.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-divided show-for-small\"  id=\"row-1934540767\">\n\n\t<div id=\"col-614109554\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 186px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:2px;color:rgb(182, 182, 182);\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"240\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0005_Professionalita\u2560et.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0005_Professionalita\u2560et.png 240w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0005_Professionalita\u2560et-150x150.png 150w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0005_Professionalita\u2560et-100x100.png 100w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Vid\u00e9os \"Comment faire\"<\/h5>\t\t\t\t\t\t\n<p>Nos vid\u00e9os \"how-to-vid\u00e9o\" expliquent le montage ou l'entretien de nos produits. <a href=\"https:\/\/www.youtube.com\/channel\/UCNkHDgEMLMyu8U7_NrlRhhQ\" target=\"_blank\" rel=\"noopener\">Ici<\/a> pour acc\u00e9der \u00e0 la cha\u00eene YouTube PTM.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1936675012\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 186px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:2px;color:rgb(182, 182, 182);\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"240\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0003_Robust.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0003_Robust.png 240w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0003_Robust-150x150.png 150w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Icon_0003_Robust-100x100.png 100w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">R\u00e9paration<\/h5>\t\t\t\t\t\t\n<p>Nous r\u00e9parons les entra\u00eenements PTM dans les 24 heures. En cas d'acc\u00e8s avant 12h, votre entra\u00eenement est m\u00eame renvoy\u00e9 le jour m\u00eame.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\n\t<section class=\"section hide-for-medium\" id=\"section_1683240765\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-1793659735\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1063\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Versuch-im-Labor-1-scaled.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-912893027\" class=\"text-box banner-layer x100 md-x100 lg-x100 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase\">Essais d'agitation<\/h3>\n<p>Dans notre laboratoire d'essai, nous r\u00e9alisons des tests d'agitation en conditions r\u00e9elles. Pour ce faire, nous avons recours \u00e0 notre gamme compl\u00e8te de produits afin de trouver la solution parfaite pour vous. Bien entendu, nous pouvons \u00e9galement nous rendre sur place. R\u00e9servez tout d'abord un rendez-vous avec l'un de nos techniciens d'application :<\/p>\n<a href=\"https:\/\/calendly.com\/ptmca\/30min\" target=\"_blank\" class=\"button primary\" rel=\"noopener\">\n\t\t<span>R\u00e9server un rendez-vous<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-912893027 {\n  width: 53%;\n}\n#text-box-912893027 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1793659735 {\n  padding-top: 650px;\n}\n#banner-1793659735 .overlay {\n  background-color: rgba(61, 70, 77, 0.488);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1683240765 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section show-for-small\" id=\"section_632595389\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n  <div class=\"banner has-hover has-video\" id=\"banner-2077065022\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                        \t<div class=\"video-overlay no-click fill hide-for-medium\"><\/div>\n\t<video class=\"video-bg fill hide-for-medium\" preload playsinline autoplay muted loop>\n\t\t<source src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/06\/Video-Ruehren-zaeher-Masse-kompr.mp4\" type=\"video\/mp4\">\t<\/video>\n            <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1082063038\" class=\"text-box banner-layer x50 md-x100 lg-x100 y10 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2 class=\"uppercase\"><span style=\"font-size: 75%;\">Essais d'agitation<\/span><\/h2>\n<p>Dans notre laboratoire d'essai, nous r\u00e9alisons des tests d'agitation en conditions r\u00e9elles. Pour ce faire, nous avons recours \u00e0 notre gamme compl\u00e8te de produits afin de trouver la solution parfaite pour vous. Bien entendu, nous pouvons \u00e9galement nous rendre sur place. R\u00e9servez tout d'abord un rendez-vous avec l'un de nos techniciens d'application :<\/p>\n<a href=\"https:\/\/calendly.com\/ptmca\/30min\" target=\"_blank\" class=\"button white\" rel=\"noopener\">\n\t\t<span>R\u00e9server un rendez-vous<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1082063038 {\n  width: 94%;\n}\n#text-box-1082063038 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1082063038 {\n    width: 53%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2077065022 {\n  padding-top: 405px;\n}\n#banner-2077065022 .overlay {\n  background-color: rgba(61, 70, 77, 0.488);\n}\n@media (min-width:550px) {\n  #banner-2077065022 {\n    padding-top: 600px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_632595389 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section show-for-medium hide-for-small\" id=\"section_238447016\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-2128277921\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"2349\" height=\"1454\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Versuch-im-Labor-ipad.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-613380451\" class=\"text-box banner-layer x95 md-x95 lg-x100 y75 md-y75 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase\">Essais d'agitation<\/h3>\n<p>Dans notre laboratoire d'essai, nous r\u00e9alisons des tests d'agitation en conditions r\u00e9elles. Pour ce faire, nous avons recours \u00e0 notre gamme compl\u00e8te de produits afin de trouver la solution parfaite pour vous. Bien entendu, nous pouvons \u00e9galement nous rendre sur place. R\u00e9servez tout d'abord un rendez-vous avec l'un de nos techniciens d'application :<\/p>\n<a href=\"https:\/\/calendly.com\/ptmca\/30min\" target=\"_blank\" class=\"button primary\" rel=\"noopener\">\n\t\t<span>R\u00e9server un rendez-vous<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-613380451 {\n  width: 54%;\n}\n#text-box-613380451 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:850px) {\n  #text-box-613380451 {\n    width: 53%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2128277921 {\n  padding-top: 600px;\n}\n#banner-2128277921 .overlay {\n  background-color: rgba(61, 70, 77, 0.634);\n}\n@media (min-width:850px) {\n  #banner-2128277921 .overlay {\n    background-color: rgba(61, 70, 77, 0.488);\n  }\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_238447016 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1948280659\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1948280659 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2900472179\" class=\"text\">\n\t\t\n<h2 class=\"ptm-heading\">Pi\u00e8ces de rechange dans le monde entier<\/h2>\n\t\t\n<style>\n#text-2900472179 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-718329463\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-718329463 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n  <div class=\"banner-grid-wrapper\">\n  <div id=\"banner-grid-2091605723\" class=\"banner-grid row row-grid show-for-medium hide-for-small row-small row-full-width\" data-packery-options=\"\">\n                      \n<div class=\"col grid-col medium-12 large-6 grid-col-1\" ><div class=\"col-inner\">\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_140227678\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"785\" height=\"520\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Weltkarte-ipad.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Weltkarte-ipad.jpg 785w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Weltkarte-ipad-300x199.jpg 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Weltkarte-ipad-768x509.jpg 768w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Weltkarte-ipad-100x66.jpg 100w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Weltkarte-ipad-447x296.jpg 447w\" sizes=\"auto, (max-width: 785px) 100vw, 785px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_140227678 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<\/div><\/div>\n<div class=\"col grid-col medium-4 large-6 grid-col-1-2\" ><div class=\"col-inner\">\n\n  <div class=\"banner has-hover\" id=\"banner-261546271\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-503432277\" class=\"text-box banner-layer x50 md-x50 lg-x50 y5 md-y5 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase\"><strong>Europe, Afrique &amp; Australie<br \/>\n<\/strong><\/h3>\n<p>PTM mechatronics GmbH<br \/>\nParc industriel 1<br \/>\n82281 Egenhofen<br \/>\nAllemagne<br \/>\nT\u00e9l : <a href=\"tel:+491834257970\">+49 8134 25 797 0<\/a><br \/>\nCourrier \u00e9lectronique : <a href=\"mailto:info@ptm-mechatronics.com\">info@ptm-mechatronics.com<\/a><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-503432277 {\n  margin: 30px 0px 0px 0px;\n  width: 97%;\n}\n#text-box-503432277 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:850px) {\n  #text-box-503432277 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-261546271 {\n  padding-top: 500px;\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n<div class=\"col grid-col medium-4 large-3 grid-col-1-2\" ><div class=\"col-inner\">\n\n  <div class=\"banner has-hover\" id=\"banner-63849428\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-257747\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y0 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase\"><strong>Am\u00e9rique<br \/>\n<\/strong><\/h3>\n<p><span style=\"font-size: 95%;\">PTM m\u00e9catronique INC<\/span><br \/>\n<span style=\"font-size: 95%;\">4100 Corporate Sqzare suite 169<br \/>\nNaples <\/span><span style=\"font-size: 95%;\">Fl 34104<br \/>\n\u00c9TATS-UNIS<\/span><br \/>\n<span style=\"font-size: 95%;\">T\u00e9l : <a href=\"tel:+12393263214\">+1 (239) 326-3214<\/a><\/span><br \/>\n<span style=\"font-size: 95%;\">Courrier \u00e9lectronique : <a href=\"mailto:support@ptm-mechatronics.com\">support@ptm-mechatronics.com<\/a>.<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-257747 {\n  margin: 40px 0px 0px 0px;\n  width: 98%;\n}\n#text-box-257747 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-63849428 {\n  padding-top: 500px;\n  background-color: rgb(61, 70, 77);\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n<div class=\"col grid-col medium-4 large-3 grid-col-1-2\" ><div class=\"col-inner\">\n\n  <div class=\"banner has-hover\" id=\"banner-2038419194\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1307529082\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y0 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase\">Asie<\/h3>\n<p>PTM m\u00e9catronique Asie<br \/>\n8 Boon Lay Way #06-13<br \/>\nTradehub 21<br \/>\nSingapour 609964<br \/>\nT\u00e9l : <a href=\"tel:+498134257970\">+49 8134 25 797 0<\/a><br \/>\nCourrier \u00e9lectronique : <a href=\"mailto:info@ptm-mechatronics.com\">info@ptm-mechatronics.com<\/a><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1307529082 {\n  margin: 40px 0px 0px 0px;\n  width: 95%;\n}\n#text-box-1307529082 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2038419194 {\n  padding-top: 500px;\n  background-color: rgb(198, 198, 198);\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n            <\/div>\n    <style>\n    #banner-grid-2091605723 .grid-col-1{height: 600px}\n    #banner-grid-2091605723 .grid-col-1-2{height: 300px}\n    #banner-grid-2091605723 .grid-col-1-3{height:200px}\n    #banner-grid-2091605723 .grid-col-2-3{height: 400px}\n    #banner-grid-2091605723 .grid-col-1-4{height: 150px}\n    #banner-grid-2091605723 .grid-col-3-4{height: 450px}\n\n\n    \n    \n\n  <\/style>\n    <\/div>\n  \n  <div class=\"banner-grid-wrapper\">\n  <div id=\"banner-grid-1905080490\" class=\"banner-grid row row-grid hide-for-medium row-small row-full-width\" data-packery-options=\"\">\n                      \n<div class=\"col grid-col medium-7 large-12 grid-col-1 hide-for-medium\" ><div class=\"col-inner\">\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1195753552\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 0px 0px 160px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"914\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Weltkarte-Hintergrund-2-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Weltkarte-Hintergrund-2-1.jpg 2000w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Weltkarte-Hintergrund-2-1-300x137.jpg 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Weltkarte-Hintergrund-2-1-1024x468.jpg 1024w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Weltkarte-Hintergrund-2-1-768x351.jpg 768w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Weltkarte-Hintergrund-2-1-1536x702.jpg 1536w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Weltkarte-Hintergrund-2-1-100x46.jpg 100w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Weltkarte-Hintergrund-2-1-447x204.jpg 447w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Weltkarte-Hintergrund-2-1-810x370.jpg 810w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1195753552 {\n  width: 81%;\n}\n<\/style>\n\t<\/div>\n\t\n<\/div><\/div>\n<div class=\"col grid-col medium-2 large-4 grid-col-1-2 hide-for-medium\" ><div class=\"col-inner\">\n\n  <div class=\"banner has-hover\" id=\"banner-922289107\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1397306487\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2 class=\"uppercase\"><strong>Europe, Afrique &amp; Australie<br \/>\n<\/strong><\/h2>\n<p>PTM mechatronics GmbH<br \/>\nParc industriel 1<br \/>\n82281 Egenhofen<br \/>\nAllemagne<br \/>\nT\u00e9l : <a href=\"tel:+491834257970\">+49 8134 25 797 0<\/a><br \/>\nCourrier \u00e9lectronique : <a href=\"mailto:info@ptm-mechatronics.com\">info@ptm-mechatronics.com<\/a><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1397306487 {\n  width: 98%;\n}\n#text-box-1397306487 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-922289107 {\n  padding-top: 500px;\n  background-color: rgb(41, 109, 173);\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n<div class=\"col grid-col medium-2 large-4 grid-col-1-2 hide-for-medium\" ><div class=\"col-inner\">\n\n  <div class=\"banner has-hover\" id=\"banner-566882995\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-707299238\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2 class=\"uppercase\"><strong>Am\u00e9rique<br \/>\n<\/strong><\/h2>\n<p><span style=\"font-size: 100%;\">PTM m\u00e9catronique INC<\/span><br \/>\n<span style=\"font-size: 100%;\">4100 Corporate Square suite 169<br \/>\nNaples Fl 34104<br \/>\n\u00c9TATS-UNIS<\/span><br \/>\n<span style=\"font-size: 100%;\">T\u00e9l : <a href=\"tel:+12393263214\">+1 239 326-3214<\/a><\/span><br \/>\n<span style=\"font-size: 95%;\"><span style=\"font-size: 100%;\">Courrier \u00e9lectronique : <\/span><a href=\"mailto:support@ptm-mechatronics.com\"><span style=\"font-size: 100%;\">support@ptm-mechatronics.com<\/span><\/a><\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-707299238 {\n  width: 98%;\n}\n#text-box-707299238 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-566882995 {\n  padding-top: 500px;\n  background-color: rgb(61, 70, 77);\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n<div class=\"col grid-col large-4 grid-col-1-2 hide-for-medium\" ><div class=\"col-inner\">\n\n  <div class=\"banner has-hover\" id=\"banner-1996894801\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1944919106\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2 class=\"uppercase\">Asie<\/h2>\n<p>PTM m\u00e9catronique Asie<br \/>\n8 Boon Lay Way #06-13<br \/>\nTradehub 21<br \/>\nSingapour 609964<br \/>\nT\u00e9l : <a href=\"tel:+498134257970\">+49 8134 25 797 0<\/a><br \/>\nCourrier \u00e9lectronique : <a href=\"mailto:info@ptm-mechatronics.com\">info@ptm-mechatronics.com<\/a><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1944919106 {\n  width: 95%;\n}\n#text-box-1944919106 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1996894801 {\n  padding-top: 500px;\n  background-color: rgb(198, 198, 198);\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n            <\/div>\n    <style>\n    #banner-grid-1905080490 .grid-col-1{height: 600px}\n    #banner-grid-1905080490 .grid-col-1-2{height: 300px}\n    #banner-grid-1905080490 .grid-col-1-3{height:200px}\n    #banner-grid-1905080490 .grid-col-2-3{height: 400px}\n    #banner-grid-1905080490 .grid-col-1-4{height: 150px}\n    #banner-grid-1905080490 .grid-col-3-4{height: 450px}\n\n\n    \n    \n\n  <\/style>\n    <\/div>\n  \n  <div class=\"banner-grid-wrapper\">\n  <div id=\"banner-grid-670172704\" class=\"banner-grid row row-grid show-for-small row-small row-full-width\" data-packery-options=\"\">\n                      \n<div class=\"col grid-col medium-4 small-12 large-6 grid-col-1-2\" ><div class=\"col-inner\">\n\n  <div class=\"banner has-hover has-video\" id=\"banner-263566363\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                        \t<div class=\"video-overlay no-click fill hide-for-medium\"><\/div>\n\t<video class=\"video-bg fill hide-for-medium\" preload playsinline autoplay muted loop>\n\t\t<source src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/06\/Video-Ruehren-zaeher-Masse-kompr.mp4\" type=\"video\/mp4\">\t<\/video>\n                        \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1145872899\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase\"><strong>Europe, Afrique &amp; Australie<br \/>\n<\/strong><\/h3>\n<p>PTM mechatronics GmbH<br \/>\nParc industriel 1<br \/>\n82281 Egenhofen<br \/>\nAllemagne<br \/>\nT\u00e9l : <a href=\"tel:+491834257970\">+49 8134 25 797 0<\/a><br \/>\nCourrier \u00e9lectronique : <a href=\"mailto:info@ptm-mechatronics.com\">info@ptm-mechatronics.com<\/a><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1145872899 {\n  margin: 10px 0px 0px 0px;\n  width: 97%;\n}\n#text-box-1145872899 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1145872899 {\n    margin: 30px 0px 0px 0px;\n  }\n}\n@media (min-width:850px) {\n  #text-box-1145872899 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-263566363 {\n  padding-top: 500px;\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n<div class=\"col grid-col medium-4 small-12 large-3 grid-col-1-2\" ><div class=\"col-inner\">\n\n  <div class=\"banner has-hover\" id=\"banner-137698859\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1968852330\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase\"><strong>Am\u00e9rique<br \/>\n<\/strong><\/h3>\n<p><span style=\"font-size: 95%;\">PTM m\u00e9catronique INC<\/span><br \/>\n<span style=\"font-size: 95%;\">4100 Corporate Sqzare suite 169<br \/>\nNaples <\/span><span style=\"font-size: 95%;\">Fl 34104<br \/>\n\u00c9TATS-UNIS<\/span><br \/>\n<span style=\"font-size: 95%;\">T\u00e9l : <a href=\"tel:+12393263214\">+1 (239) 326-3214<\/a><\/span><br \/>\n<span style=\"font-size: 95%;\">Courrier \u00e9lectronique : <a href=\"mailto:support@ptm-mechatronics.com\">support@ptm-mechatronics.com<\/a>.<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1968852330 {\n  margin: 10px 0px 0px 0px;\n  width: 98%;\n}\n#text-box-1968852330 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1968852330 {\n    margin: 40px 0px 0px 0px;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-137698859 {\n  padding-top: 500px;\n  background-color: rgb(61, 70, 77);\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n<div class=\"col grid-col medium-4 small-12 large-3 grid-col-1-2\" ><div class=\"col-inner\">\n\n  <div class=\"banner has-hover\" id=\"banner-1060990733\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1985423704\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase\">Asie<\/h3>\n<p>PTM m\u00e9catronique Asie<br \/>\n8 Boon Lay Way #06-13<br \/>\nTradehub 21<br \/>\nSingapour 609964<br \/>\nT\u00e9l : <a href=\"tel:+498134257970\">+49 8134 25 797 0<\/a><br \/>\nCourrier \u00e9lectronique : <a href=\"mailto:info@ptm-mechatronics.com\">info@ptm-mechatronics.com<\/a><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1985423704 {\n  margin: 10px 0px 0px 0px;\n  width: 95%;\n}\n#text-box-1985423704 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1985423704 {\n    margin: 40px 0px 0px 0px;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1060990733 {\n  padding-top: 500px;\n  background-color: rgb(198, 198, 198);\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n            <\/div>\n    <style>\n    #banner-grid-670172704 .grid-col-1{height: 600px}\n    #banner-grid-670172704 .grid-col-1-2{height: 300px}\n    #banner-grid-670172704 .grid-col-1-3{height:200px}\n    #banner-grid-670172704 .grid-col-2-3{height: 400px}\n    #banner-grid-670172704 .grid-col-1-4{height: 150px}\n    #banner-grid-670172704 .grid-col-3-4{height: 450px}\n\n\n    \n    \n\n  <\/style>\n    <\/div>\n  \n\n\t<section class=\"section homepage-faq-section\" id=\"section_1743878953\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-middle align-center\"  id=\"row-1817480615\">\n\n\t<div id=\"col-1552711998\" class=\"col small-12 large-12 medium-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1615381020\" class=\"text\">\n\t\t\n<h2 class=\"ptm-heading\">FAQ'S<\/h2>\n\t\t\n<style>\n#text-1615381020 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1552711998 > .col-inner {\n  padding: 30px 0px 20px 0px;\n}\n@media (min-width:850px) {\n  #col-1552711998 > .col-inner {\n    padding: 50px 0px 20px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-233756476\" class=\"col pb-0 medium-9 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(41, 109, 173);\" >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2652702008\" class=\"text\">\n\t\t\n<h2>Vous souhaitez acheter des techniques d'entra\u00eenement ou d'agitation ? <em>Nous r\u00e9pondons \u00e0 vos questions !<\/em><\/h2>\n\t\t\n<style>\n#text-2652702008 {\n  color: rgb(255, 255, 255);\n}\n#text-2652702008 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/fr\/faq\/\" target=\"_blank\" class=\"button white\" rel=\"noopener\" >\n\t\t<span>Plus de FAQ<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-233756476 > .col-inner {\n  padding: 40px 30px 40px 30px;\n  margin: 0px 0px 0px 0px;\n}\n@media (min-width:850px) {\n  #col-233756476 > .col-inner {\n    margin: 0px 30px 30px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1352933954\" class=\"col medium-9 small-12 large-6 medium-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"accordion tzn-accordion\">\n\t<div id=\"accordion-1674226649\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1674226649-label\" class=\"accordion-title plain\" href=\"#accordion-item-wo-finde-ich-technische-daten,-abmessungen-und-zertifikate?\" aria-expanded=\"false\" aria-controls=\"accordion-1674226649-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Basculer\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>O\u00f9 puis-je trouver des donn\u00e9es techniques, des dimensions et des certificats ?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1674226649-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1674226649-label\">\n\t\t\t\n<p>Vous trouverez les fiches techniques, les modes d'emploi et les certificats pour chaque produit sous la rubrique T\u00e9l\u00e9chargements.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-75366913\" class=\"accordion-item\">\n\t\t<a id=\"accordion-75366913-label\" class=\"accordion-title plain\" href=\"#accordion-item-wo-finde-ich-cad-dateien-zu-den-motoren?\" aria-expanded=\"false\" aria-controls=\"accordion-75366913-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Basculer\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>O\u00f9 puis-je trouver des fichiers CAD pour les moteurs ?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-75366913-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-75366913-label\">\n\t\t\t\n<div class=\"et_pb_toggle_content clearfix\">\n<p>Les fichiers CAD sont disponibles pour chaque mod\u00e8le de moteur sous la rubrique T\u00e9l\u00e9chargements.<\/p>\n<p>Dans le dossier de t\u00e9l\u00e9chargement se trouvent les diff\u00e9rents sous-ensembles et un guide PDF qui vous montre comment configurer le moteur.<\/p>\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2717228621\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2717228621-label\" class=\"accordion-title plain\" href=\"#accordion-item-wie-w\u00e4hle-ich-die-richtige-motorengr\u00f6\u00dfe-und-das-richtige-getriebe?\" aria-expanded=\"false\" aria-controls=\"accordion-2717228621-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Basculer\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Comment choisir la bonne taille de moteur et la bonne transmission ?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2717228621-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2717228621-label\">\n\t\t\t\n<div class=\"et_pb_toggle_content clearfix\">\n<p>Pour configurer le moteur, il faut d'abord d\u00e9finir le couple n\u00e9cessaire \u00e0 l'application. Pour nos moteurs, nous indiquons le couple de d\u00e9marrage. Nous entendons par l\u00e0 le couple que le moteur d\u00e9veloppe lorsqu'il d\u00e9marre. C'est l\u00e0 que le couple est le plus \u00e9lev\u00e9. Lorsque la vitesse de rotation augmente, le couple diminue l\u00e9g\u00e8rement.<\/p>\n<p>Cela signifie que le deuxi\u00e8me facteur \u00e0 d\u00e9finir est la vitesse ou la plage de vitesse n\u00e9cessaire pour l'application. Pour conna\u00eetre le couple et les plages de vitesse de rotation de nos moteurs, veuillez consulter les donn\u00e9es de puissance. <a href=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2022\/10\/Leistungsdaten-Motor.pdf\" target=\"_blank\" rel=\"noopener\">ici<\/a>.<\/p>\n<p>En outre, trois bo\u00eetes de vitesses sont disponibles, qui influencent le couple et le r\u00e9gime :<\/p>\n<ul>\n<li>Un r\u00e9ducteur 3:1 triple le couple du moteur ; en m\u00eame temps, la plage de vitesse n'est plus que de 1\/3 de celle du moteur sans r\u00e9ducteur.<\/li>\n<li>Un r\u00e9ducteur 9:1 multiplie par neuf le couple du moteur ; en m\u00eame temps, la plage de vitesse n'est plus que de 1\/9 de celle du moteur sans r\u00e9ducteur.<\/li>\n<li>Une bo\u00eete de vitesses 1:2 r\u00e9duit de moiti\u00e9 le couple du moteur, tout en doublant la plage de r\u00e9gime \u00e0 600 tr\/min au lieu de 300.<\/li>\n<\/ul>\n<p>Pour les tr\u00e8s faibles vitesses de rotation, il est avantageux d'utiliser un r\u00e9ducteur 3:1 ou 9:1, car le mouvement de rotation se d\u00e9roule ainsi de mani\u00e8re plus r\u00e9guli\u00e8re que sans r\u00e9ducteur. Un moteur standard ne tourne r\u00e9guli\u00e8rement et sans \u00e0-coups qu'\u00e0 partir d'environ 30 tr\/min. Avec un r\u00e9ducteur 3:1, le moteur tourne de mani\u00e8re r\u00e9guli\u00e8re et sans \u00e0-coups \u00e0 partir d'environ 10 1\/min et avec un r\u00e9ducteur 9:1, \u00e0 partir d'environ 3 1\/min.<\/p>\n<p>Pour illustrer les r\u00e9flexions \u00e0 mener, voici deux exemples pratiques :<\/p>\n<p>Exemple 1 :<br \/>\nJ'ai besoin d'une vitesse de rotation de 400 tr\/min avec un couple de 2Nm.<\/p>\n<p>Une transmission 1:2 est n\u00e9cessaire pour atteindre les 400 1\/min. Pour atteindre les 2Nm \u00e0 400 1\/min, le moteur 0900 sera n\u00e9cessaire. Le moteur 0900 avec un r\u00e9ducteur 1:2 a une plage de vitesse de 0-600 1\/min et un couple de d\u00e9marrage de 4Nm. A 400 1\/min, le moteur fournit les 2Nm souhait\u00e9s.<\/p>\n<p><strong>Exemple 2 :<br \/>\n<\/strong>J'ai besoin d'une vitesse de rotation de 20 tr\/min avec un couple de 12Nm.<\/p>\n<p>Un r\u00e9ducteur 3:1 est n\u00e9cessaire pour atteindre les 20 1\/min de mani\u00e8re r\u00e9guli\u00e8re et sans \u00e0-coups. Pour atteindre les 12Nm \u00e0 20 1\/min, le moteur 0450 sera n\u00e9cessaire. Le moteur 0450 avec un r\u00e9ducteur 3:1 a une plage de vitesse de 0 \u00e0 100 1\/min et un couple de d\u00e9marrage de 12Nm. A 20 1\/min, le moteur fournit les 12Nm souhait\u00e9s.<\/p>\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3128773603\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3128773603-label\" class=\"accordion-title plain\" href=\"#accordion-item-passt-der-motor-zu-meiner-anwendung?\" aria-expanded=\"false\" aria-controls=\"accordion-3128773603-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Basculer\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Le moteur est-il adapt\u00e9 \u00e0 mon application ?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3128773603-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3128773603-label\">\n\t\t\t\n<p>Nos moteurs sont des machines incompl\u00e8tes non \u00e9lectriques au sens de la directive sur la construction des machines et servent d'entra\u00eenement dans les machines et les installations pour actionner des roues, des rouleaux, des brosses, des agitateurs, des convoyeurs \u00e0 bande et \u00e0 vis, etc. En outre, ils peuvent entra\u00eener des vannes et des soupapes ainsi que des portes roulantes, etc.<\/p>\n<p>Nous nous ferons un plaisir de vous conseiller en d\u00e9tail et de discuter de votre application.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1424424244\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1424424244-label\" class=\"accordion-title plain\" href=\"#accordion-item-gibt-es-unterschiedliche-dichtungskonzepte?\" aria-expanded=\"false\" aria-controls=\"accordion-1424424244-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Basculer\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Existe-t-il diff\u00e9rents concepts d'\u00e9tanch\u00e9it\u00e9 ?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1424424244-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1424424244-label\">\n\t\t\t\n<div class=\"et_pb_toggle_content clearfix\">\n<p>Tous nos joints sont exempts de silicone. Nous proposons quatre joints diff\u00e9rents :<\/p>\n<p>NBR - est notre standard<br \/>\nViton - pour une temp\u00e9rature \u00e9lev\u00e9e et une r\u00e9sistance chimique<br \/>\nPTFE - r\u00e9sistant aux solvants pour une utilisation \u00e0 long terme<br \/>\nConforme aux normes FDA - en PTFE blanc, homologu\u00e9 par la FDA pour une utilisation hygi\u00e9nique dans l'industrie alimentaire et pharmaceutique<\/p>\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3931100546\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3931100546-label\" class=\"accordion-title plain\" href=\"#accordion-item-welche-druckluft-wird-ben\u00f6tigt?\" aria-expanded=\"false\" aria-controls=\"accordion-3931100546-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Basculer\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Quel type d'air comprim\u00e9 est n\u00e9cessaire ?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3931100546-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3931100546-label\">\n\t\t\t\n<p>Le fluide utilis\u00e9 est de l'air comprim\u00e9 trait\u00e9, non lubrifi\u00e9, \u00e0 2-6 bar, avec une classe de qualit\u00e9 5 selon ISO 8573-1 degr\u00e9 de filtration &lt;=5\u03bc.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3001501037\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3001501037-label\" class=\"accordion-title plain\" href=\"#accordion-item-kann-ich-die-motoren-auch-mit-anderen-medien-betreiben?\" aria-expanded=\"false\" aria-controls=\"accordion-3001501037-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Basculer\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Puis-je faire fonctionner les moteurs avec d'autres fluides ?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3001501037-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3001501037-label\">\n\t\t\t\n<p>L'utilisation de liquides et de gaz n'est pas conforme \u00e0 l'utilisation pr\u00e9vue de nos moteurs. Nous nous ferons un plaisir de v\u00e9rifier votre application \u00e0 cet \u00e9gard. Dans la mesure du possible, nous pouvons autoriser l'utilisation de certains gaz dans nos moteurs.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1352933954 > .col-inner {\n  margin: 0px 0px 0px 0px;\n}\n@media (min-width:850px) {\n  #col-1352933954 > .col-inner {\n    margin: 0px 0px 0px 30px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1743878953 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(239, 239, 239);\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-559274608\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-559274608 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":13441,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-12303","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ptm-mechatronics.com\/fr\/wp-json\/wp\/v2\/pages\/12303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptm-mechatronics.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ptm-mechatronics.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ptm-mechatronics.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ptm-mechatronics.com\/fr\/wp-json\/wp\/v2\/comments?post=12303"}],"version-history":[{"count":26,"href":"https:\/\/ptm-mechatronics.com\/fr\/wp-json\/wp\/v2\/pages\/12303\/revisions"}],"predecessor-version":[{"id":13442,"href":"https:\/\/ptm-mechatronics.com\/fr\/wp-json\/wp\/v2\/pages\/12303\/revisions\/13442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ptm-mechatronics.com\/fr\/wp-json\/wp\/v2\/media\/13441"}],"wp:attachment":[{"href":"https:\/\/ptm-mechatronics.com\/fr\/wp-json\/wp\/v2\/media?parent=12303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}