{"id":15999,"date":"2026-01-28T11:12:58","date_gmt":"2026-01-28T10:12:58","guid":{"rendered":"https:\/\/ptm-mechatronics.com\/?page_id=15999"},"modified":"2026-05-07T08:56:17","modified_gmt":"2026-05-07T06:56:17","slug":"dokumentation","status":"publish","type":"page","link":"https:\/\/ptm-mechatronics.com\/es\/dokumentation\/","title":{"rendered":"Documentaci\u00f3n"},"content":{"rendered":"<div class=\"banner has-hover\" id=\"banner-304905902\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-973868679\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h1><span style=\"font-size: 90%;\">Documentaci\u00f3n<\/span><\/h1>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-973868679 {\n  width: 60%;\n}\n#text-box-973868679 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-304905902 {\n  padding-top: 200px;\n}\n<\/style>\n  <\/div>\n\n\n\n\t<section class=\"section\" id=\"section_1459538776\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-small align-equal\"  id=\"row-1100160593\">\n\n\t<div id=\"col-42489469\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(41, 109, 173);\" >\n\t\t\t\n\t\t\t\n\t<div id=\"text-130239694\" class=\"text\">\n\t\t\n<p>Modelo<\/p>\n\t\t\n<style>\n#text-130239694 {\n  text-align: center;\n  color: rgb(255, 255, 255);\n}\n#text-130239694 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-42489469 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-225579595\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(41, 109, 173);\" >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2363573365\" class=\"text\">\n\t\t\n<p>Documento<\/p>\n\t\t\n<style>\n#text-2363573365 {\n  text-align: center;\n  color: rgb(255, 255, 255);\n}\n#text-2363573365 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-225579595 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-761138880\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(41, 109, 173);\" >\n\t\t\t\n\t\t\t\n\t<div id=\"text-361499973\" class=\"text\">\n\t\t\n<p>Idioma<\/p>\n\t\t\n<style>\n#text-361499973 {\n  text-align: center;\n  color: rgb(255, 255, 255);\n}\n#text-361499973 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-761138880 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1170186116\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(41, 109, 173);\" >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1569619585\" class=\"text\">\n\t\t\n<p>descargar<\/p>\n\t\t\n<style>\n#text-1569619585 {\n  text-align: center;\n  color: rgb(255, 255, 255);\n}\n#text-1569619585 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1170186116 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-small align-equal\"  id=\"row-1121140073\">\n\n\t<div id=\"col-1458470664\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Motores neum\u00e1ticos<br \/>BASIC, ATEX, INOX, IP67<br \/>0450\/0900\/1800\/3600\/7200<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1458470664 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1173868540\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Instrucciones de montaje y funcionamiento<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1173868540 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-31361263\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Alem\u00e1n \/ Ingl\u00e9s<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-31361263 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-716383326\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2026\/01\/PMO_V4.pdf\" target=\"_blank\" class=\"button primary expand\" rel=\"noopener\" style=\"border-radius:10px;\">\n\t\t<span>Manual de instrucciones V4<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-small align-equal\"  id=\"row-1693980593\">\n\n\t<div id=\"col-1113679653\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>El agitador acciona el neum\u00e1tico.<br \/>eco, eco-Drive<br \/>0450\/0900\/1800\/3600\/6500<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1113679653 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1431367729\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Instrucciones de montaje y funcionamiento<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1431367729 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-763834980\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Alem\u00e1n \/ Ingl\u00e9s<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-763834980 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1357288714\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2026\/01\/eco_V2.pdf\" target=\"_blank\" class=\"button primary expand\" rel=\"noopener\" style=\"border-radius:10px;\">\n\t\t<span>Manual de instrucciones V2<\/span>\n\t<\/a>\n\n<a href=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2026\/04\/eco_V3.pdf\" target=\"_blank\" class=\"button primary expand\" rel=\"noopener\" style=\"border-radius:10px;\">\n\t\t<span>Manual de instrucciones V3<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-small align-equal\"  id=\"row-1556051328\">\n\n\t<div id=\"col-1722405562\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>El agitador acciona el neum\u00e1tico.<br \/>eco-Seal light, eco-Seal pro, eco-Seal INOX<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1722405562 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-2115193732\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Instrucciones de uso<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2115193732 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-238650628\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Alem\u00e1n \/ Ingl\u00e9s<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-238650628 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1789717854\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2026\/01\/Seal_V3.pdf\" target=\"_blank\" class=\"button primary expand\" rel=\"noopener\" style=\"border-radius:10px;\">\n\t\t<span>Manual de instrucciones V3<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-small align-equal\"  id=\"row-1295264271\">\n\n\t<div id=\"col-1645446217\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Agitador acciona electr.<br \/>eDrive<br \/>1200\/1600<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1645446217 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1716395877\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Instrucciones de uso<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1716395877 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1718951512\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Alem\u00e1n \/ Ingl\u00e9s<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1718951512 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1934957138\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2026\/01\/e-Drive_V1.pdf\" target=\"_blank\" class=\"button primary expand\" rel=\"noopener\" style=\"border-radius:10px;\">\n\t\t<span>Manual de instrucciones V1<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-small align-equal\"  id=\"row-1162487196\">\n\n\t<div id=\"col-1868492862\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Agitador de laboratorio<br \/>eco-Lab<br \/>450\/450G\/900\/900G<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1868492862 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-492000171\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Instrucciones de uso<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-492000171 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1783465566\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Alem\u00e1n \/ Ingl\u00e9s<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1783465566 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1068187105\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2026\/01\/Lab_V1.pdf\" target=\"_blank\" class=\"button primary expand\" rel=\"noopener\" style=\"border-radius:10px;\">\n\t\t<span>Manual de instrucciones V1<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-small align-equal\"  id=\"row-2105114316\">\n\n\t<div id=\"col-1600096639\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Batidora de mano<br \/>eco-Up<br \/>450\/900\/900G\/1800<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1600096639 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1691599599\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Instrucciones de uso<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1691599599 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-343513504\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Alem\u00e1n \/ Ingl\u00e9s<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-343513504 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-362148259\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2026\/01\/Up_V1.pdf\" target=\"_blank\" class=\"button primary expand\" rel=\"noopener\" style=\"border-radius:10px;\">\n\t\t<span>Manual de instrucciones V1<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-small align-equal\"  id=\"row-1619344351\">\n\n\t<div id=\"col-981179564\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Sistema de cambio r\u00e1pido de los ejes agitadores<br \/>eco-Quick V2, V3, V4<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-981179564 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1165471065\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Instrucciones de uso<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1165471065 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-16434398\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Alem\u00e1n \/ Ingl\u00e9s<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-16434398 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1363282854\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2026\/04\/EQ_V2-V3-V4.pdf\" target=\"_blank\" class=\"button primary expand\" rel=\"noopener\" style=\"border-radius:10px;\">\n\t\t<span>Manual de instrucciones V1<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-small align-equal\"  id=\"row-333558773\">\n\n\t<div id=\"col-856736465\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>batidora de pie eco-Station pro<br \/>10-60 litros \/ 30-200 litros \/ 60-1000 litros<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-856736465 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-376477339\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Instrucciones de montaje y funcionamiento<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-376477339 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1947979847\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(239, 239, 239);\" >\n\t\t\t\n\t\t\t\n<p>Alem\u00e1n \/ Ingl\u00e9s<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1947979847 > .col-inner {\n  padding: 10px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-487433634\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2026\/05\/eco-Station_pro_V1.pdf\" target=\"_blank\" class=\"button primary expand\" rel=\"noopener\" style=\"border-radius:10px;\">\n\t\t<span>Manual de instrucciones V1<\/span>\n\t<\/a>\n\n<a href=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2026\/05\/Konformitaetserklaerung-eco-Station-pro.pdf\" target=\"_blank\" class=\"button primary expand\" rel=\"noopener\" style=\"border-radius:10px;\">\n\t\t<span>Declaraci\u00f3n de conformidad<\/span>\n\t<\/a>\n\n<a href=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2026\/05\/ATEX-Certification-eco-Station-Pro.pdf\" target=\"_blank\" class=\"button primary expand\" rel=\"noopener\" style=\"border-radius:10px;\">\n\t\t<span>Certificado ATEX<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1459538776 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section st-kontakt pt-60 pb-60 col-pb-0\" id=\"section_1398929675\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"444\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/BG_kontakt.png\" class=\"bg attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n<div class=\"row\"  id=\"row-1152199175\">\r\n\r\n\n\t<div id=\"col-901059610\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div id=\"text-405265907\" class=\"text\">\n\t\t\r\n\r\n<h3>Contacto y asesoramiento<\/h3>\r\n<p>\u00bfDesea asesoramiento sobre nuestros productos? Nuestros expertos estar\u00e1n encantados de atender su solicitud:<\/p>\r\n<h4><a href=\"mailto:info@ptm-mechatronics.com\">info@ptm-mechatronics.com<\/a><br \/>\r\n<a href=\"tel:+498134257970\">+49 8134 \/ 25 797 0<\/a><\/h4>\r\n\t\t\n<style>\n#text-405265907 {\n  color: rgb(255, 255, 255);\n}\n#text-405265907 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1398929675 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n#section_1398929675 .section-bg img {\n  object-position: 84% 53%;\n}\n<\/style>\n\t<\/section>\n\t\r\n\n\t<section class=\"section pb-60 pt-60 besuchen\" id=\"section_268986770\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n<div class=\"row align-center\"  id=\"row-1617600406\">\r\n\r\n\n\t<div id=\"col-1785417887\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div id=\"text-2289745150\" class=\"text title-box\">\n\t\t\r\n\r\n<h3>Tambi\u00e9n puede visitarnos en<\/h3>\r\n\t\t\n<style>\n#text-2289745150 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n<div class=\"row align-middle align-center\" style=\"max-width:605px\" id=\"row-960867625\">\r\n\r\n\n\t<div id=\"col-843625224\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_205712874\">\n\t\t<a class=\"\" href=\"https:\/\/www.linkedin.com\/company\/68597546\/\" target=\"_blank\" rel=\"noopener\">\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"209\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/PTM-mechatronics-bei-LinkedIn-480x209-1.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/PTM-mechatronics-bei-LinkedIn-480x209-1.png 480w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/PTM-mechatronics-bei-LinkedIn-480x209-1-300x131.png 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/PTM-mechatronics-bei-LinkedIn-480x209-1-100x44.png 100w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/PTM-mechatronics-bei-LinkedIn-480x209-1-447x195.png 447w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_205712874 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1970615349\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_512368892\">\n\t\t<a class=\"\" href=\"https:\/\/www.xing.com\/pages\/ptm-mechatronics-gmbh\" target=\"_blank\" rel=\"noopener\">\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"130\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Xing-1-e1530203231869-300x130-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Xing-1-e1530203231869-300x130-1.jpg 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Xing-1-e1530203231869-300x130-1-100x43.jpg 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_512368892 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-888462299\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_472538917\">\n\t\t<a class=\"\" href=\"https:\/\/www.youtube.com\/@ptmmechatronicsgmbh806\" target=\"_blank\" rel=\"noopener\">\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"133\" src=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Youtube-1-e1530203212402-300x133-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Youtube-1-e1530203212402-300x133-1.jpg 300w, https:\/\/ptm-mechatronics.com\/wp-content\/uploads\/2024\/10\/Youtube-1-e1530203212402-300x133-1-100x44.jpg 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_472538917 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_268986770 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-15999","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ptm-mechatronics.com\/es\/wp-json\/wp\/v2\/pages\/15999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptm-mechatronics.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ptm-mechatronics.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ptm-mechatronics.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ptm-mechatronics.com\/es\/wp-json\/wp\/v2\/comments?post=15999"}],"version-history":[{"count":8,"href":"https:\/\/ptm-mechatronics.com\/es\/wp-json\/wp\/v2\/pages\/15999\/revisions"}],"predecessor-version":[{"id":16259,"href":"https:\/\/ptm-mechatronics.com\/es\/wp-json\/wp\/v2\/pages\/15999\/revisions\/16259"}],"wp:attachment":[{"href":"https:\/\/ptm-mechatronics.com\/es\/wp-json\/wp\/v2\/media?parent=15999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}